{"id":19426,"date":"2021-12-06T13:01:20","date_gmt":"2021-12-06T18:01:20","guid":{"rendered":"https:\/\/wordpress.world.dan.org\/?post_type=dan_alert_diver&#038;p=19426"},"modified":"2023-06-19T10:43:12","modified_gmt":"2023-06-19T14:43:12","slug":"program-spotlight-dan-courses-3-0-update","status":"publish","type":"dan_alert_diver","link":"https:\/\/world.dan.org\/es\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/","title":{"rendered":"FOCO DE ATENCI\u00d3N DEL PROGRAMA: actualizaci\u00f3n de los cursos de DAN 3.0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Est\u00e1 en la embarcaci\u00f3n despu\u00e9s de un excelente buceo cuando un equipo de compa\u00f1eros sale a la superficie y uno de ellos pide ayuda. La tripulaci\u00f3n del barco ayuda al buzo accidentado a subir a bordo. \u00bfSabr\u00eda qu\u00e9 hacer a continuaci\u00f3n? Sin importar cu\u00e1l sea su nivel de capacitaci\u00f3n de buceo, o incluso si no es buzo y debe lidiar con un incidente en tierra, la capacitaci\u00f3n en primeros auxilios de DAN puede ayudarlo a saber qu\u00e9 hacer y c\u00f3mo hacerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En noviembre, en DAN lanzamos la versi\u00f3n 3.0 de nuestros cursos de capacitaci\u00f3n en primeros auxilios. La nueva versi\u00f3n refleja los protocolos internacionales actuales para realizar una reanimaci\u00f3n cardiopulmonar (RCP), proporcionar primeros auxilios y adquirir otras habilidades relacionadas. Los cursos se centran en el soporte de vida b\u00e1sico, el ox\u00edgeno para emergencias y los primeros auxilios para los profesionales de buceo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso Soporte de vida b\u00e1sico: RCP y primeros auxilios abarca la RCP para adultos, ni\u00f1os y beb\u00e9s realizada por uno o dos rescatistas. Asimismo, incluye el uso de un desfibrilador autom\u00e1tico externo y c\u00f3mo abordar una obstrucci\u00f3n de v\u00edas a\u00e9reas por cuerpo extra\u00f1o. Las habilidades de primeros auxilios incluyen detener hemorragias por diversos medios, lo que incluye presi\u00f3n directa, vendaje de heridas y torniquetes. El curso tambi\u00e9n incluye primeros auxilios para tratar diversas afecciones m\u00e9dicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ox\u00edgeno para emergencias para accidentes de buceo sigue siendo el curso principal de DAN. Los estudiantes aprenden cu\u00e1ndo y c\u00f3mo suministrar ox\u00edgeno a buzos y v\u00edctimas de eventos de inmersi\u00f3n mediante el uso de una m\u00e1scara de no-reinhalaci\u00f3n, una v\u00e1lvula de demanda, una m\u00e1scara con v\u00e1lvula de bolsa o un ventilador de presi\u00f3n positiva (MTV).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso Primeros auxilios de buceo para profesionales de buceo, pero cualquier persona puede beneficiarse de las habilidades que pueden aplicarse fuera del \u00e1mbito de buceo. El curso incorpora todas las habilidades de los otros dos cursos y agrega ex\u00e1menes neurol\u00f3gicos y c\u00f3mo tratar lesiones causadas por vida marina peligrosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para inscribirse en un curso y para buscar un instructor DAN cerca de usted, visite&nbsp;<em><a href=\"http:\/\/dan.dan.org\/education-events\/instructor-led-courses\" target=\"_blank\" rel=\"noreferrer noopener\">DAN.org\/education-events\/cursos dirigidos por instructores<\/a><\/em>.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">\u00a9&nbsp;<em>Alert Diver<\/em>&nbsp;- Q3\/Q4 2021<\/p>","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 en la embarcaci\u00f3n despu\u00e9s de un excelente buceo cuando un equipo de compa\u00f1eros sale a la superficie y uno de ellos pide ayuda. La tripulaci\u00f3n del barco ayuda al buzo accidentado a subir a bordo. \u00bfSabr\u00eda qu\u00e9 hacer a continuaci\u00f3n? Sin importar cu\u00e1l sea su nivel de capacitaci\u00f3n de buceo, o incluso si no es buzo y debe lidiar con un incidente en tierra, la capacitaci\u00f3n en primeros auxilios de DAN puede ayudarlo a saber qu\u00e9 hacer y c\u00f3mo hacerlo.<\/p>","protected":false},"featured_media":19432,"template":"","dan_alert_diver_categories":[66],"dan_alert_diver_issues":[474],"class_list":["post-19426","dan_alert_diver","type-dan_alert_diver","status-publish","has-post-thumbnail","hentry","dan_alert_diver_categories-dive-slate","dan_alert_diver_issues-q3-q4-2021"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PROGRAM SPOTLIGHT: DAN Courses 3.0 Update - DAN World<\/title>\n<meta name=\"description\" content=\"In November, DAN launched version 3.0 of our first aid training courses. The new version reflects current international protocols for performing cardiopulmonary resuscitation (CPR), first aid and related skills.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROGRAM SPOTLIGHT: DAN Courses 3.0 Update\" \/>\n<meta property=\"og:description\" content=\"In November, DAN launched version 3.0 of our first aid training courses. The new version reflects current international protocols for performing cardiopulmonary resuscitation (CPR), first aid and related skills. Courses focus on basic life support, emergency oxygen and first aid for dive professionals.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/\" \/>\n<meta property=\"og:site_name\" content=\"DAN World\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-19T14:43:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/dan-first-aid-training-1200x.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"In November, DAN launched version 3.0 of our first aid training courses. The new version reflects current international protocols for performing cardiopulmonary resuscitation (CPR), first aid and related skills.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/program-spotlight-dan-courses-3-0-update\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/program-spotlight-dan-courses-3-0-update\\\/\",\"name\":\"PROGRAM SPOTLIGHT: DAN Courses 3.0 Update - DAN World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/program-spotlight-dan-courses-3-0-update\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/program-spotlight-dan-courses-3-0-update\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dan-first-aid-training-1200x.jpeg\",\"datePublished\":\"2021-12-06T18:01:20+00:00\",\"dateModified\":\"2023-06-19T14:43:12+00:00\",\"description\":\"In November, DAN launched version 3.0 of our first aid training courses. The new version reflects current international protocols for performing cardiopulmonary resuscitation (CPR), first aid and related skills.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/program-spotlight-dan-courses-3-0-update\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/program-spotlight-dan-courses-3-0-update\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/program-spotlight-dan-courses-3-0-update\\\/#primaryimage\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dan-first-aid-training-1200x.jpeg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dan-first-aid-training-1200x.jpeg\",\"width\":1200,\"height\":800,\"caption\":\"DAN first aid training\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/program-spotlight-dan-courses-3-0-update\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/world.dan.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROGRAM SPOTLIGHT: DAN Courses 3.0 Update\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"name\":\"DAN World\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/world.dan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\",\"name\":\"DAN World\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"width\":175,\"height\":52,\"caption\":\"DAN World\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PROGRAMA DESTACADO: Cursos DAN 3.0 - DAN World","description":"En noviembre, DAN lanz\u00f3 la versi\u00f3n 3.0 de nuestros cursos de formaci\u00f3n en primeros auxilios. La nueva versi\u00f3n refleja los protocolos internacionales actuales para realizar reanimaci\u00f3n cardiopulmonar (RCP), primeros auxilios y habilidades relacionadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/world.dan.org\/es\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/","og_locale":"es_MX","og_type":"article","og_title":"PROGRAM SPOTLIGHT: DAN Courses 3.0 Update","og_description":"In November, DAN launched version 3.0 of our first aid training courses. The new version reflects current international protocols for performing cardiopulmonary resuscitation (CPR), first aid and related skills. Courses focus on basic life support, emergency oxygen and first aid for dive professionals.","og_url":"https:\/\/world.dan.org\/es\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/","og_site_name":"DAN World","article_modified_time":"2023-06-19T14:43:12+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/dan-first-aid-training-1200x.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"In November, DAN launched version 3.0 of our first aid training courses. The new version reflects current international protocols for performing cardiopulmonary resuscitation (CPR), first aid and related skills.","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/world.dan.org\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/","url":"https:\/\/world.dan.org\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/","name":"PROGRAMA DESTACADO: Cursos DAN 3.0 - DAN World","isPartOf":{"@id":"https:\/\/world.dan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/#primaryimage"},"image":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/#primaryimage"},"thumbnailUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/dan-first-aid-training-1200x.jpeg","datePublished":"2021-12-06T18:01:20+00:00","dateModified":"2023-06-19T14:43:12+00:00","description":"En noviembre, DAN lanz\u00f3 la versi\u00f3n 3.0 de nuestros cursos de formaci\u00f3n en primeros auxilios. La nueva versi\u00f3n refleja los protocolos internacionales actuales para realizar reanimaci\u00f3n cardiopulmonar (RCP), primeros auxilios y habilidades relacionadas.","breadcrumb":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/world.dan.org\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/#primaryimage","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/dan-first-aid-training-1200x.jpeg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/dan-first-aid-training-1200x.jpeg","width":1200,"height":800,"caption":"DAN first aid training"},{"@type":"BreadcrumbList","@id":"https:\/\/world.dan.org\/alert-diver\/article\/program-spotlight-dan-courses-3-0-update\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/world.dan.org\/"},{"@type":"ListItem","position":2,"name":"PROGRAM SPOTLIGHT: DAN Courses 3.0 Update"}]},{"@type":"WebSite","@id":"https:\/\/world.dan.org\/es\/#website","url":"https:\/\/world.dan.org\/es\/","name":"DAN World","description":"","publisher":{"@id":"https:\/\/world.dan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/world.dan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/world.dan.org\/es\/#organization","name":"DAN World","url":"https:\/\/world.dan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","width":175,"height":52,"caption":"DAN World"},"image":{"@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver\/19426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver"}],"about":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/types\/dan_alert_diver"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media\/19432"}],"wp:attachment":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media?parent=19426"}],"wp:term":[{"taxonomy":"dan_alert_diver_categories","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_categories?post=19426"},{"taxonomy":"dan_alert_diver_issues","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_issues?post=19426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}