{"id":19441,"date":"2021-12-07T15:20:26","date_gmt":"2021-12-07T20:20:26","guid":{"rendered":"https:\/\/wordpress.world.dan.org\/?post_type=dan_alert_diver&#038;p=19441"},"modified":"2023-06-06T17:44:32","modified_gmt":"2023-06-06T21:44:32","slug":"celebrating-seagrass","status":"publish","type":"dan_alert_diver","link":"https:\/\/world.dan.org\/es\/alert-diver\/article\/celebrating-seagrass\/","title":{"rendered":"Celebremos los pastos marinos"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-why-protecting-this-disappearing-marine-plant-is-vital-in-our-fight-to-save-the-climate-and-biodiversity\">Por qu\u00e9 proteger esta planta marina que est\u00e1 desapareciendo es fundamental en nuestra lucha por salvar el clima y la biodiversidad.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Levant\u00e9 la roca y mi llave hab\u00eda desaparecido. Era un mediod\u00eda de julio y el calor de los Cayos de la Florida era agobiante. Estaba empapado y ten\u00eda algas marinas en el cabello. Mi tel\u00e9fono, billetera, agua potable, llave del hotel, gafas de sol y todo lo dem\u00e1s, con excepci\u00f3n de mi traje de ba\u00f1o mojado y mi c\u00e1mara submarina, estaban en el caluroso autom\u00f3vil de alquiler, que estaba cerrado. Sab\u00eda que hab\u00eda puesto el llavero all\u00ed, y hab\u00eda estado observando el \u00e1rea desde el agua. Nadie podr\u00eda haberla tomado y me preguntaba, incr\u00e9dulo, d\u00f3nde demonios podr\u00eda estar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00eda estado sentado en una pradera de pastos marinos, con la esperanza de que un t\u00edmido tibur\u00f3n cabeza de pala nadara en frente de mi lente. Estos tiburones martillo peque\u00f1os fueron clasificados en 2018 como los primeros tiburones omn\u00edvoros conocidos del mundo. Una pregunta central a la que se enfrentaban los cient\u00edficos era qu\u00e9 cantidad del contenido de nutrientes de los pastos marinos estaban tomando los tiburones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un estudio dirigido por Samantha Leigh, Ph.D., de la Universidad Estatal de California, Dominguez Hills (California State University, Dominguez Hills), investigadores les dieron a tiburones cabeza de pala cautivos una dieta con un 90 por ciento de pastos marinos por tres semanas. Un an\u00e1lisis de la digesti\u00f3n de los tiburones mostr\u00f3 que pod\u00edan obtener nutrientes de los pastos marinos y manifestaban un crecimiento con una dieta principalmente vegetariana. Debido a que otros omn\u00edvoros marinos hab\u00edan tenido efectos positivos sobre las cadenas alimentarias, los investigadores plantearon que la ingesta de nutrientes de los tiburones implicaba que \u201cdeber\u00edamos reevaluar las funciones de los tiburones cabeza de pala en la ecolog\u00eda de los pastos marinos porque podr\u00edan ser responsables de un pastoreo significativo y el transporte de nutrientes dentro de los fr\u00e1giles ecosistemas de pastos marinos\u201d.<sup>1<\/sup><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/dan.org\/wp-content\/uploads\/2021\/11\/school-of-fish-feed-in-seagrass-800.jpg\" alt=\"Un banco de peces se alimenta en las praderas marinas\" class=\"wp-image-28209\"\/><figcaption class=\"wp-element-caption\">Un banco de peces se alimenta de pastos marinos.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los tiburones consumidores de plantas son solo un ejemplo de c\u00f3mo la ciencia cambia nuestro parecer de los pastos marinos y pone de manifiesto su importancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los pastos marinos son diferentes a las algas marinas; son m\u00e1s similares a las plantas florales que crecen en tierra. Hay aproximadamente 72 especies en aguas costeras en todos los continentes, excepto la Ant\u00e1rtida, desde el ecuador hasta las \u00e1reas fr\u00edas&nbsp;<em>Zostera marina<\/em><em>&nbsp;<\/em>crece en el \u00c1rtico y puede sobrevivir bajo el hielo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unas semanas antes de perder la llave en el calor de Florida, estaba usando un traje seco, pero aun as\u00ed temblando en agua con una temperatura de 1 \u00b0C (35 \u00b0F) en Terranova, Canad\u00e1. Me hab\u00eda unido a un peque\u00f1o equipo de cient\u00edficos de Pesquer\u00edas y Oc\u00e9anos de Canad\u00e1 (Fisheries and Oceans Canada, DFO), que han estado monitoreando las poblaciones de peces y zostera marina durante d\u00e9cadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios de la d\u00e9cada de 1990, una de las pesquer\u00edas m\u00e1s grandes del mundo colaps\u00f3. Una moratoria de 1992 sobre la pesca de bacalao se cobr\u00f3 m\u00e1s de 30.000 puestos de trabajo en Terranova. La poblaci\u00f3n de bacalao del Atl\u00e1ntico hab\u00eda sido mal gestionada y fue objeto de una grave sobrepesca. En los casi 30 a\u00f1os que han transcurrido desde entonces, la poblaci\u00f3n no ha vuelto a alcanzar niveles donde la pesca comercial pueda desarrollarse como alguna vez lo hizo. Tener abundantes h\u00e1bitats de pastos marinos donde los j\u00f3venes puedan esconderse y alimentarse es fundamental para aumentar las cantidades de bacalao.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/dan.org\/wp-content\/uploads\/2021\/11\/green-sea-turtle-seagrass-researcher-Bahamas-800.jpg\" alt=\"tortuga verde\" class=\"wp-image-28210\"\/><figcaption class=\"wp-element-caption\">Una tortuga marina verde se topa con un investigador de pastos marinos en las Bahamas.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas de las principales especies para la pesca del mundo dependen de los pastos marinos en alg\u00fan momento de su ciclo de vida. Aproximadamente el 70 por ciento de las especies pesqueras de Florida, por ejemplo, pasan un tiempo en los pastos marinos.<sup>2<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que los tiburones cabeza de pala, los bacalaos del Atl\u00e1ntico son t\u00edmidos cuando hay personas. Prepar\u00e9 mi equipo fotogr\u00e1fico submarino en un tr\u00edpode en frente de una exuberante \u00e1rea de pastos marinos y me alej\u00e9, y con la mano congelada agarr\u00e9 el disparador remoto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un diminuto bacalao del Atl\u00e1ntico revoloteaba ocasionalmente frente a mi lente y yo tomaba una fotograf\u00eda. Entre buceos y sorbos de chocolate caliente, bromeaba con el equipo sobre mi pr\u00f3ximo viaje a la soleada Espa\u00f1a despu\u00e9s de eso, a la vez que intentaba lograr que entraran en calor y sintieran celos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cerca de la costa espa\u00f1ola del mar Mediterr\u00e1neo, nad\u00e9 entre una de las especies de pastos marinos m\u00e1s antiguos y grandes del planeta&nbsp;<em>Posidonia oce\u00e1nica<\/em>El sistema de ra\u00edces de la planta est\u00e1 conectado debajo del lecho marino y se extiende por m\u00e1s de 14 km (9 millas). Los cient\u00edficos estiman que este organismo podr\u00eda tener hasta 200.000 a\u00f1os. La especie ha tenido una lenta recuperaci\u00f3n tras la p\u00e9rdida y ha disminuido debido al cambio clim\u00e1tico y otras actividades humanas. Los investigadores est\u00e1n reuniendo datos sobre su p\u00e9rdida y las \u00e1reas donde no est\u00e1 disminuyendo, con la esperanza de que una mejor comprensi\u00f3n ayude a revertir la tendencia.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/dan.org\/wp-content\/uploads\/2021\/11\/Propeller-scars-Florida-Keys-can-cut-past-roots-inflict-long-term-damage-800.jpg\" alt=\"Cicatrices de h\u00e9lices en los Cayos de Florida\" class=\"wp-image-28211\"\/><figcaption class=\"wp-element-caption\">Las marcas de h\u00e9lices, como \u00e9stas en los Cayos de la Florida, pueden cortar por debajo de las ra\u00edces y causar da\u00f1os a largo plazo en la pradera.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los pastos marinos est\u00e1n disminuyendo en todo el mundo. Algunas estimaciones sugieren una p\u00e9rdida total de hasta un 7 por ciento al a\u00f1o durante la d\u00e9cada de 1990 y principios de la d\u00e9cada de 2000.<sup>3<\/sup>&nbsp;Factores como poluci\u00f3n, desarrollo costero, menor claridad del agua, algunas actividades de pesca, acciones de amarre y pr\u00e1cticas de navegaci\u00f3n, y, desde luego, el cambio clim\u00e1tico, se encuentran entre aquellos que contribuyen a la disminuci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mayo de 2019, me un\u00ed a un equipo de voluntarios e investigadores del Instituto de Ciencias Marinas de Virginia (Virginia Institute of Marine Science, VIMS) para continuar con un proyecto de restauraci\u00f3n de pastos marinos de 20 a\u00f1os mediante una t\u00e9cnica desarrollada por el profesor de VIMS Robert \u201cJJ\u201d Orth, Ph.D. Su sistema de siembra es incre\u00edblemente eficaz y ha restablecido m\u00e1s de 9.000 acres de zostera saludable que ha mostrado signos de desarrollo para convertirse en un ecosistema completo. Este m\u00e9todo puede ser prometedor para un rebrote en otros lugares, pero proteger lo que a\u00fan tenemos deber\u00eda ser la prioridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los beneficios de proteger los pastos marinos no deben subestimarse. Los pastos marinos purifican el agua, ayudan a proteger contra la erosi\u00f3n costera, ayudan a mantener las pesquer\u00edas de peque\u00f1a escala que sustentan comunidades y aumentan las poblaciones de peces y la biodiversidad. Absorben mucho m\u00e1s carbono por \u00e1rea que los bosques terrestres y reducen la acidificaci\u00f3n del oc\u00e9ano. Tener pastos marinos saludables se traduce en un oc\u00e9ano m\u00e1s pr\u00f3spero.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/dan.org\/wp-content\/uploads\/2021\/11\/volunteer-Nature-Conservancy-collects-eelgrass-flowering-shoots-800.jpg\" alt=\"\" class=\"wp-image-28212\"\/><figcaption class=\"wp-element-caption\">Un voluntario de Nature Conservancy toma un pu\u00f1ado de tallos florales de zostera para recolectar semillas para el proyecto de restauraci\u00f3n de pastos marinos m\u00e1s grande del mundo.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Con todas estas ventajas, \u00bfpor qu\u00e9 los turistas no est\u00e1n acudiendo en manada para explorar las praderas de pastos marinos? He tenido encuentros con cocodrilos y tiburones con dientes afilados, adorables dugongos y tortugas, incre\u00edbles caballitos de mar y pulpos, extra\u00f1os peces grumo y cangrejos herradura y muchas otras criaturas entre los pastos marinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Florida, un solo tibur\u00f3n cabeza de pala eventualmente nad\u00f3 frente a mi c\u00e1mara, ech\u00f3 una r\u00e1pida mirada y desapareci\u00f3. Ten\u00eda una sola fotograf\u00eda que pod\u00eda usar despu\u00e9s de nueve d\u00edas de esperar pacientemente. Nunca encontr\u00e9 mi llave. Un cangrejo probablemente la arrastro por uno de los muchos hoyos cercanos \u2014quiz\u00e1s fue una peque\u00f1a venganza de la naturaleza. Si nos permitimos destruir gran parte de la naturaleza, me preocupa su represalia contra todos nosotros. Hagamos lo que podamos para proteger nuestros pastos marinos \u2014esa es una llave que no queremos perder.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-notes\"><strong>Notas<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">1. Leigh SC, Papastamatiou YP, German DP. Seagrass digestion by a notorious \u2018carnivore.\u2019 Proceedings of the Royal Society B. 2018; 285(1886). doi.org\/10.1098\/rspb.2018.1583.&nbsp;<em><a href=\"http:\/\/royalsocietypublishing.org\/doi\/full\/10.1098\/rspb.2018.1583\" target=\"_blank\" rel=\"noreferrer noopener\">royalsocietypublishing.org\/doi\/full\/10.1098\/rspb.2018.1583<\/a><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Importancia de las praderas marinas. Comisi\u00f3n de Conservaci\u00f3n de la Pesca y la Vida Silvestre de Florida.&nbsp;<em><a href=\"http:\/\/myfwc.com\/research\/habitat\/seagrasses\/information\/importance\" target=\"_blank\" rel=\"noreferrer noopener\">myfwc.com\/research\/habitat\/seagrasses\/information\/importance<\/a><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Salinas C, Duarte CM, Lavery PS, et al. Seagrass losses since mid-20th century fueled CO<sub>2<\/sub>&nbsp;de las reservas de carbono del suelo.&nbsp;<em>Biolog\u00eda del cambio global<\/em>&nbsp;2020; 26(9):4772\u20134784. doi.org\/10.1111\/gcb.15204.&nbsp;<em><a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/full\/10.1111\/gcb.15204\">onlinelibrary.wiley.com\/doi\/full\/10.1111\/gcb.15204<\/a><\/em><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-dan-light-gray-color has-alpha-channel-opacity has-dan-light-gray-background-color has-background is-style-wide\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-explore-more\"><strong>Explore M\u00e1s<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vea este v\u00eddeo para saber m\u00e1s sobre el papel de las praderas marinas en el cambio clim\u00e1tico.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Pastos marinos: una soluci\u00f3n inesperada al cambio clim\u00e1tico\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/zY2WCPwkmog?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">\u00a9&nbsp;<em>Alert Diver<\/em>&nbsp;- Q3\/Q4 2021<\/p>","protected":false},"excerpt":{"rendered":"<p>Los beneficios de proteger los pastos marinos no deben subestimarse. Los pastos marinos purifican el agua, ayudan a proteger contra la erosi\u00f3n costera, ayudan a mantener las pesquer\u00edas de peque\u00f1a escala que sustentan comunidades y aumentan las poblaciones de peces y la biodiversidad. Absorben mucho m\u00e1s carbono por \u00e1rea que los bosques terrestres y reducen la acidificaci\u00f3n del oc\u00e9ano. Tener pastos marinos saludables se traduce en un oc\u00e9ano m\u00e1s pr\u00f3spero.<\/p>","protected":false},"featured_media":19443,"template":"","dan_alert_diver_categories":[70],"dan_alert_diver_issues":[474],"class_list":["post-19441","dan_alert_diver","type-dan_alert_diver","status-publish","has-post-thumbnail","hentry","dan_alert_diver_categories-water-planet","dan_alert_diver_issues-q3-q4-2021"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Celebrating Seagrass - DAN World<\/title>\n<meta name=\"description\" content=\"Why protecting this disappearing marine plant is vital in our fight to save the climate and biodiversity.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/celebrating-seagrass\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrating Seagrass\" \/>\n<meta property=\"og:description\" content=\"Why protecting this disappearing marine plant is vital in our fight to save the climate and biodiversity.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/celebrating-seagrass\/\" \/>\n<meta property=\"og:site_name\" content=\"DAN World\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T21:44:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/bonnethead-sharks-ingest-copious-amounts-of-seagrass-while-feeding-on-crabs-1200.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Why protecting this disappearing marine plant is vital in our fight to save the climate and biodiversity.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/celebrating-seagrass\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/celebrating-seagrass\\\/\",\"name\":\"Celebrating Seagrass - DAN World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/celebrating-seagrass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/celebrating-seagrass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/bonnethead-sharks-ingest-copious-amounts-of-seagrass-while-feeding-on-crabs-1200.jpeg\",\"datePublished\":\"2021-12-07T20:20:26+00:00\",\"dateModified\":\"2023-06-06T21:44:32+00:00\",\"description\":\"Why protecting this disappearing marine plant is vital in our fight to save the climate and biodiversity.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/celebrating-seagrass\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/celebrating-seagrass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/celebrating-seagrass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/bonnethead-sharks-ingest-copious-amounts-of-seagrass-while-feeding-on-crabs-1200.jpeg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/bonnethead-sharks-ingest-copious-amounts-of-seagrass-while-feeding-on-crabs-1200.jpeg\",\"width\":1200,\"height\":800,\"caption\":\"bonnethead sharks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/celebrating-seagrass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/world.dan.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrating Seagrass\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"name\":\"DAN World\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/world.dan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\",\"name\":\"DAN World\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"width\":175,\"height\":52,\"caption\":\"DAN World\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Celebrando la hierba marina - DAN World","description":"Por qu\u00e9 proteger esta planta marina que est\u00e1 desapareciendo es fundamental en nuestra lucha por salvar el clima y la biodiversidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/world.dan.org\/es\/alert-diver\/article\/celebrating-seagrass\/","og_locale":"es_MX","og_type":"article","og_title":"Celebrating Seagrass","og_description":"Why protecting this disappearing marine plant is vital in our fight to save the climate and biodiversity.","og_url":"https:\/\/world.dan.org\/es\/alert-diver\/article\/celebrating-seagrass\/","og_site_name":"DAN World","article_modified_time":"2023-06-06T21:44:32+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/bonnethead-sharks-ingest-copious-amounts-of-seagrass-while-feeding-on-crabs-1200.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"Why protecting this disappearing marine plant is vital in our fight to save the climate and biodiversity.","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/world.dan.org\/alert-diver\/article\/celebrating-seagrass\/","url":"https:\/\/world.dan.org\/alert-diver\/article\/celebrating-seagrass\/","name":"Celebrando la hierba marina - DAN World","isPartOf":{"@id":"https:\/\/world.dan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/celebrating-seagrass\/#primaryimage"},"image":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/celebrating-seagrass\/#primaryimage"},"thumbnailUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/bonnethead-sharks-ingest-copious-amounts-of-seagrass-while-feeding-on-crabs-1200.jpeg","datePublished":"2021-12-07T20:20:26+00:00","dateModified":"2023-06-06T21:44:32+00:00","description":"Por qu\u00e9 proteger esta planta marina que est\u00e1 desapareciendo es fundamental en nuestra lucha por salvar el clima y la biodiversidad.","breadcrumb":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/celebrating-seagrass\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/world.dan.org\/alert-diver\/article\/celebrating-seagrass\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/alert-diver\/article\/celebrating-seagrass\/#primaryimage","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/bonnethead-sharks-ingest-copious-amounts-of-seagrass-while-feeding-on-crabs-1200.jpeg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2021\/12\/bonnethead-sharks-ingest-copious-amounts-of-seagrass-while-feeding-on-crabs-1200.jpeg","width":1200,"height":800,"caption":"bonnethead sharks"},{"@type":"BreadcrumbList","@id":"https:\/\/world.dan.org\/alert-diver\/article\/celebrating-seagrass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/world.dan.org\/"},{"@type":"ListItem","position":2,"name":"Celebrating Seagrass"}]},{"@type":"WebSite","@id":"https:\/\/world.dan.org\/es\/#website","url":"https:\/\/world.dan.org\/es\/","name":"DAN World","description":"","publisher":{"@id":"https:\/\/world.dan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/world.dan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/world.dan.org\/es\/#organization","name":"DAN World","url":"https:\/\/world.dan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","width":175,"height":52,"caption":"DAN World"},"image":{"@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver\/19441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver"}],"about":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/types\/dan_alert_diver"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media\/19443"}],"wp:attachment":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media?parent=19441"}],"wp:term":[{"taxonomy":"dan_alert_diver_categories","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_categories?post=19441"},{"taxonomy":"dan_alert_diver_issues","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_issues?post=19441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}