{"id":22869,"date":"2022-08-25T11:13:30","date_gmt":"2022-08-25T15:13:30","guid":{"rendered":"https:\/\/world.dan.org\/?post_type=dan_alert_diver&#038;p=22869"},"modified":"2023-02-08T15:54:50","modified_gmt":"2023-02-08T20:54:50","slug":"the-maldives","status":"publish","type":"dan_alert_diver","link":"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-maldives\/","title":{"rendered":"Las Maldivas"},"content":{"rendered":"<p class=\"has-medium-font-size wp-block-paragraph\"><span style=\"color: #005274;\" class=\"stk-highlight\"><strong>SI BIEN EL MUNDO A\u00daN ESTABA MAYORMENTE CONFINADO<\/strong>&nbsp;<\/span><span style=\"color: #111111;\" class=\"stk-highlight\">con restricciones de viaje, mis redes sociales estaban repletas de maravillosas fotos de las Maldivas. Las Maldivas abrieron antes que la mayor\u00eda de los destinos de buceo extranjeros, por lo que hab\u00eda mucha inspiraci\u00f3n fotogr\u00e1fica para nuestro viaje en mayo. La cobertura en l\u00ednea inclu\u00eda los tiburones ballena, mantarrayas, tiburones tigre y arrecifes tropicales coloridos que esper\u00e1bamos estuvieran esper\u00e1ndonos.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo lo que deb\u00edamos hacer era llegar all\u00ed, algo sencillo seg\u00fan los est\u00e1ndares de viajes de buceo ex\u00f3ticos. Un vuelo directo de Miami a Doha, Catar, demor\u00f3 14 horas, y luego una conexi\u00f3n de cinco horas me llev\u00f3 al aeropuerto internacional de Mal\u00e9, la capital de las Maldivas. Si bien eso es mucho tiempo, en especial si consideramos la escala en Doha, tambi\u00e9n es sencillo, lo que vuelve a las Maldivas m\u00e1s accesibles que la mayor\u00eda de los destinos de buceo de clase mundial. Si bien Miami era conveniente para m\u00ed, otros miembros de nuestro grupo partieron desde Nueva York, Seattle, Houston y Los \u00c1ngeles. Existen otras v\u00edas de acceso estadounidenses y europeas a las Maldivas, que depende del turismo. El f\u00e1cil acceso a\u00e9reo es el lubricante que mantiene las ruedas del comercio en movimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Mal\u00e9, una lancha o un avi\u00f3n puede trasladar a los visitantes a un centro tur\u00edstico en tierra en una de las muchas islas bordeadas por arena blanca \u2014hay 1.192 islas registradas en 26 atolones en toda la regi\u00f3n de las Maldivas\u2014. Al igual que nosotros en este viaje, usted tambi\u00e9n puede subirse a una embarcaci\u00f3n de vida a bordo para disfrutar de uno de los muchos itinerarios posibles. Sin importar c\u00f3mo lo haga, las oportunidades de buceo est\u00e1n alejadas de la congesti\u00f3n de la capital y en medio de un mar azul. Afortunadamente, estar lejos de la capital no significa necesariamente que sea un viaje a un lugar distante \u2014hay buenos puntos de buceo a un viaje en barco de menos de 30 minutos y por todo el archipi\u00e9lago\u2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una breve vista general de la estructura de los arrecifes de las Maldivas ayuda a explicar las oportunidades de buceo. Las Maldivas incluyen monta\u00f1as volc\u00e1nicas sumergidas, lo que proporcion\u00f3 el sustrato para la colonizaci\u00f3n de corales. Los atolones de coral bajos se formaron sobre estos picos y el aumento cada vez mayor de los niveles del mar dieron lugar a extensos arrecifes perif\u00e9ricos. En la actualidad, estas islas son solo las cimas de monta\u00f1as sumergidas y est\u00e1n en riesgo de que el mar (geogr\u00e1ficamente hablando) las sumerja en breve. Hay grandes desarrollos de apartamentos en construcci\u00f3n en Mal\u00e9 para albergar a residentes de las islas perif\u00e9ricas que est\u00e1n perdiendo tierra, pero el turismo contin\u00faa creciendo a pesar del problema de infraestructura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El buceo var\u00eda seg\u00fan si se encuentra en un canal, faru, thila o giri. Los buzos normalmente ingresan al agua en los canales situados entre el mar abierto y las lagunas en una corriente entrante por dos motivos: lleva el agua del mar azul a trav\u00e9s del canal, y una marea saliente lo arrastrar\u00eda hacia el vasto oc\u00e9ano en lugar de una laguna tranquila y protegida, donde es m\u00e1s f\u00e1cil y seguro volver a subir a la embarcaci\u00f3n de buceo.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_82_maldives.jpeg\" alt=\"Un dhoni de buceo se acerca al arrecife poco profundo\" class=\"wp-image-22873\" width=\"615\" height=\"410\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_82_maldives.jpeg 432w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_82_maldives-360x240.jpeg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_82_maldives-18x12.jpeg 18w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Un dhoni de buceo se acerca lentamente al arrecife superficial frente al oc\u00e9ano \u00cdndico,<\/span> <span style=\"color: #005274;\" class=\"stk-highlight\">y un canal conduce a una laguna protegida.<\/span><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_77_maldives.jpeg\" alt=\"morena\" class=\"wp-image-22874\" width=\"615\" height=\"441\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_77_maldives.jpeg 648w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_77_maldives-360x258.jpeg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_77_maldives-18x12.jpeg 18w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">En el punto de buceo conocido como Fish Tank es com\u00fan ver morenas de diferentes especies cohabitando en las mismas grietas del arrecife.<\/span><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"288\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_78_maldives.jpeg\" alt=\"Un pez \u00e1ngel\" class=\"wp-image-22875\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_78_maldives.jpeg 432w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_78_maldives-360x240.jpeg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_78_maldives-18x12.jpeg 18w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><figcaption class=\"wp-element-caption\"><strong>Un majestuoso pez \u00e1ngel visita una estaci\u00f3n de limpieza en Fahalla Thila.<\/strong><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los farus son arrecifes circulares que se elevan del lecho marino, normalmente dentro de un canal. La corriente y los nutrientes que se desplazan con cada cambio de la marea indican que hay muchos farus buenos con crecimiento de corales blandos. En una marea \u00f3ptima, se puede observar una buena acci\u00f3n pel\u00e1gica en el punto de encuentro de las corrientes. Un thila comienza en aguas m\u00e1s superficiales dentro de los atolones y puede ser lo suficiente peque\u00f1o como para circunnavegarlo en un buceo. El giri a menudo es m\u00e1s peque\u00f1o, pero estos t\u00e9rminos con frecuencia son intercambiables. Ambos carecen de la estructura circular y, en cambio, presentan un promontorio superficial con una concentraci\u00f3n de coral.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es relevante porque el tipo de buceo depende de la marea, d\u00f3nde est\u00e1 situada la estructura en relaci\u00f3n con el canal y si es un \u00e1rea protegida de la corriente. Para nuestro grupo de fot\u00f3grafos algunos de los buceos a la deriva a trav\u00e9s de los canales resultaron poco productivos. Si bien hab\u00eda muchas cosas para fotografiar, era dif\u00edcil detenerse el tiempo suficiente para montar la escena. A menudo opt\u00e1bamos por un buceo en un arrecife tranquilo en lugar de un buceo a la deriva a alta velocidad. Las Maldivas brindan abundantes opciones dependiendo de las preferencias del grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mal\u00e9 se encuentra en el extremo sur de&nbsp;<strong>Mal del Norte<\/strong><strong>\u00e9<\/strong><strong>&nbsp;Atol\u00f3n<\/strong>, y esta \u00e1rea est\u00e1 bien explorada, con docenas de puntos de buceo de calidad. Iniciar nuestra expedici\u00f3n aqu\u00ed permiti\u00f3 que las maletas que no hab\u00edan llegado en el vuelo internacional arribaran mientras a\u00fan est\u00e1bamos cerca del aeropuerto.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se puede alejar mucho m\u00e1s para comenzar, y diversos itinerarios de embarcaciones de vida a bordo han evolucionado para respaldar intereses de buceo espec\u00edficos. Un itinerario en el sur puede aumentar la probabilidad de tener alg\u00fan encuentro con tiburones.&nbsp;<strong>Addu<\/strong>&nbsp;(El mundo submarino de Jacques Cousteau) y los documentales&nbsp;<strong>Fuvamulah<\/strong>&nbsp;son conocidos por la presencia de tiburones tigre, guitarra, azotadores, martillo, oce\u00e1nicos de puntas negras, ballena y de puntas plateadas, adem\u00e1s de mantas gigantes y de arrecife. Si bien eso suena emocionante, no ir\u00edamos muy al sur esta vez, pero puede ser el itinerario para mi pr\u00f3xima visita.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-style-large is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><span style=\"color: #005274;\" class=\"stk-highlight\">Las Maldivas incluyen monta\u00f1as volc\u00e1nicas sumergidas, lo que proporcion\u00f3 el sustrato para la colonizaci\u00f3n de corales. Los atolones de coral bajos se formaron sobre estos picos y el aumento cada vez mayor de los niveles del mar dieron lugar a extensos arrecifes perif\u00e9ricos.<\/span><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El pa\u00eds es tan vasto en lo que se refiere a atracciones marinas que es imposible equivocarse sin importar d\u00f3nde navegue su embarcaci\u00f3n de vida a bordo. El archipi\u00e9lago abarca casi 90.649 kil\u00f3metros cuadrados (35.000 millas cuadradas), y se extiende m\u00e1s de 820,8 kil\u00f3metros (510 millas) de norte a sur y 128,7 kil\u00f3metros (80 millas) de este a oeste. A medida que se aleja de Mal\u00e9, puede elegir entre itinerarios populares, incluso los atolones Ari y Rasdhoo o quiz\u00e1s Baa Atoll, que es famoso por la enorme cantidad de mantarrayas que a menudo residen en la Bah\u00eda de Hanifaru entre julio y noviembre. O tal vez quiera dirigirse al sur para visitar Mulaku, Vaavu y Kolhumadulu, que es lo que hicimos nosotros en mi viaje a las Maldivas en 2016.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las embarcaciones que parten de Mal\u00e9 pueden seguir una ruta circular ya sea en sentido horario o antihorario. Nosotros elegimos navegar en sentido antihorario para permanecer dentro del alcance del aeropuerto y comenzamos con&nbsp;<strong>Rasdhoo Madivaru.&nbsp;<\/strong>El buceo de verificaci\u00f3n nos ayud\u00f3 a ajustar nuestra flotabilidad y repasar habilidades de buceo que se hab\u00edan deteriorado durante las restricciones de viaje. Sin esperar demasiado, ingres\u00e9 al agua con una lente macro de 50 mm pensando que la claridad del agua ser\u00eda reducida, pero que al menos habr\u00eda buenos peces. Los peces no me decepcionaron, y la visibilidad me sorprendi\u00f3. Ten\u00edamos una claridad de al menos 24 metros (80 pies) y una temperatura del agua de 29 \u00b0C (84 \u00b0F), por lo que estaba muy c\u00f3modo con mi traje de 3 mm. Casi inmediatamente encontr\u00e9 un gran banco de pargos de rayas azules y uno de mis habitantes del arrecife del Indo-Pac\u00edfico favoritos: el pez ballesta payaso. Meros de coral y peces mariposa de nariz larga decoraban el arrecife inclinado, mientras an\u00e9monas hu\u00e9sped y sus peces payaso residentes proporcionaban sujetos dispuestos a pulir las habilidades fotogr\u00e1ficas algo olvidadas de nuestro grupo.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_79_maldives-e1660318360657.png\" alt=\"Michael Aw fotografi\u00f3 este tibur\u00f3n tigre\" class=\"wp-image-22876\" width=\"614\" height=\"484\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_79_maldives-e1660318360657.png 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_79_maldives-e1660318360657-15x12.png 15w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"288\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_80_maldives.jpeg\" alt=\"Tibur\u00f3n ballena aliment\u00e1ndose de camarones y plancton\" class=\"wp-image-22877\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_80_maldives.jpeg 432w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_80_maldives-360x240.jpeg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_80_maldives-18x12.jpeg 18w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><figcaption class=\"wp-element-caption\"><span style=\"color: #005274;\" class=\"stk-highlight\"><strong>Las luces brillantes situadas en la parte posterior de la plataforma de buceo a veces atraen camarones y plancton, que, del mismo modo, pueden atraer al ic\u00f3nico organismo filtrador: el tibur\u00f3n ballena.<\/strong><br><\/span><br><span style=\"color: #005274;\" class=\"stk-highlight\"><br><strong>Michael Aw fotografi\u00f3 a este tibur\u00f3n tigre en las islas del sur de las Maldivas.<\/strong><\/span><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Me sorprendi\u00f3 que nuestro segundo buceo ser\u00eda en una estaci\u00f3n de limpieza de mantas en North Ari Atoll porque ten\u00eda el potencial de ser un punto destacado de cualquier viaje de buceo en las Maldivas. Cre\u00ed que la tripulaci\u00f3n guardar\u00eda las oportunidades excepcionales para m\u00e1s adelante en la semana, pero la direcci\u00f3n de nuestro viaje cambi\u00f3 sus prioridades. La estaci\u00f3n de limpieza fue verdaderamente espectacular, no solo por la interacci\u00f3n de las mantas, sino por las criaturas que encontramos mientras esper\u00e1bamos la llegada de las mantas. De acuerdo con nuestro informe de seguridad, la marea dominante nos indicar\u00eda qu\u00e9 lado de una formaci\u00f3n de coral superficial en particular deb\u00eda ocupar nuestro grupo. Los peces que limpiaban las mantas resid\u00edan all\u00ed, as\u00ed que lo \u00fanico que ten\u00edamos que hacer era esperar y no abrumar a las mantas cuando finalmente llegaran.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La espera podr\u00eda haber sido tediosa si no hubiera sido por el gran banco de pargos rojos jorobados en la periferia de la cabeza de coral. Nuestra disciplina para permanecer en el lugar y esperar la acci\u00f3n fue puesta a prueba cuando una tranquila raya \u00e1guila lleg\u00f3 all\u00ed y toler\u00f3 que yo nadara junto a ella a 60 cent\u00edmetros (2 pies) de distancia. Al darme cuenta de que cuanto m\u00e1s nadara con la raya \u00e1guila, m\u00e1s tendr\u00eda que nadar para regresar a la estaci\u00f3n de limpieza cuando llegaran las mantas, di la vuelta justo a tiempo para ver a las mantas acerc\u00e1ndose desde alg\u00fan lugar que solo ellas conoc\u00edan. El grupo hizo exactamente lo que la tripulaci\u00f3n de buceo nos hab\u00eda dicho: permanecer en el fondo y dejar que las mantas se acercaran a nosotros.&nbsp;&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-style-large is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><span style=\"color: #005274;\" class=\"stk-highlight\">Tal como predijo la tripulaci\u00f3n, un joven tibur\u00f3n ballena vino a cenar. Med\u00eda quiz\u00e1s 5,5 metros (18 pies) y definitivamente no se ir\u00eda a ninguna otra parte mientras se sirviera comida. Ten\u00edamos todo el tiempo que quisi\u00e9ramos para hacer snorkel con el tibur\u00f3n ballena. Horas m\u00e1s tarde nos fuimos a la cama con el tibur\u00f3n ballena a\u00fan en la popa.<\/span><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando me acomod\u00e9 nuevamente, observ\u00e9 que una de las mantas se desplazaba a pocos cent\u00edmetros por encima de la cubierta tipo domo de mi amiga Paula Selby. Obtuve algunas im\u00e1genes estupendas de la interacci\u00f3n desde el costado, pero sent\u00ed envidia de la posici\u00f3n estrat\u00e9gica de Paula hasta que vi la extensi\u00f3n de su cubierta y me di cuenta de que deb\u00eda estar fotografiando con una lente de zoom de 16-35 mm. Eso es bastante amplio para la mayor\u00eda de las cosas, pero el vientre de una manta a 15 cm (6 pulgadas) de la cubierta no ser\u00eda m\u00e1s que una manta blanca colocada desde arriba. Aun as\u00ed, fue una experiencia sensacional para ella, y continu\u00f3 as\u00ed por dos minutos. Felizmente, la manta hizo un c\u00edrculo alrededor de ella, lo que le permiti\u00f3 obtener una vista lateral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los siguientes dos buceos en&nbsp;<strong>Bathala Thila<\/strong>&nbsp;(El mundo submarino de Jacques Cousteau) y los documentales&nbsp;<strong>Hafsa Thila<\/strong>&nbsp;requirieron un poco de autocontrol porque hab\u00eda tantas an\u00e9monas diferentes amontonadas con sus coloridos mantos expuestos, y \u00bfcu\u00e1ntas puedes fotografiar en tu vida? Aparentemente algunas docenas m\u00e1s, a juzgar por la carpeta de im\u00e1genes de Maldivas de ese d\u00eda. Al menos fotografi\u00e9 algunos peces ballesta payaso y soldados raya-negra m\u00e1s para agregar un poco de variedad al d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El buceo nocturno en&nbsp;<strong>Maaya Thila<\/strong>&nbsp;fue una anomal\u00eda del agua cristalina que hab\u00edamos tenido m\u00e1s temprano ese d\u00eda; con la marea saliente, la visibilidad no pudo haber sido de m\u00e1s de 9 metros (30 pies). Intentamos caer en un pin\u00e1culo, pero no pudimos verlo y nos perdimos la cima. Mientras reacomodaba mi boya de superficie que se hab\u00eda inflado accidentalmente, descend\u00ed de manera constante a mayor profundidad hasta que me encontr\u00e9 arrodillado en el fondo de arena a (\u00a1ay!) 35 metros (116 pies). Esto demuestra que hacer 6.000 buceos no evita las insensateces, pero el descenso profundo no nos perjudic\u00f3. Mi compa\u00f1ero de buceo y yo regresamos a la cima del pin\u00e1culo a 7,6 metros (25 pies), donde deb\u00edamos estar, y fotografiamos rayas jaspeadas, jureles y tiburones de arrecife de puntas blancas.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_81_maldives.jpeg\" alt=\"corales blandos en Fohtheyo Kandu\" class=\"wp-image-22878\" width=\"615\" height=\"373\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_81_maldives.jpeg 475w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_81_maldives-360x218.jpeg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_81_maldives-18x12.jpeg 18w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Valerie Rutledge utiliza su iPhone en una caja estanca SeaLife SportDiver para fotografiar corales blandos en Fohtheyo Kandu.<\/span> <span style=\"color: #005274;\" class=\"stk-highlight\">fotografiar corales blandos en Fohtheyo Kandu.<\/span><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El buceo matutino continu\u00f3 con nuestra trayectoria hacia el sur hacia&nbsp;<strong>Cabeza de pez<\/strong>un punto de buceo en<strong>&nbsp;Mushimasmigili Thila.&nbsp;<\/strong>Era m\u00e1s similar a Fish Soup debido al banco de \u00eddolos moros que anulaban la luz en el punto de encuentro de las corrientes de la isla. Tambi\u00e9n tuve encuentros estupendos con una d\u00f3cil tortuga carey y un gran banco de pargos de rayas azules. Ese es un punto de buceo que hubiera vuelto a visitar, pero fue bueno debido a la marea entrante, y la energ\u00eda hubiera amainado con la marea tranquila. Fue mejor dejarlo en la memoria \u2014y en las tarjetas de memoria\u2014 y avanzar a la siguiente aventura, otra estaci\u00f3n de limpieza de mantarrayas en&nbsp;<strong>Rocas de Mahibadhoo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los protocolos se mantuvieron pr\u00e1cticamente iguales, y nuestro grupo se situ\u00f3 a lo largo de la periferia de la corriente descendente del arrecife superficial. En este buceo, Tracey Bennett obtuvo el beneficio del vientre de la manta que descendi\u00f3 sobre su domo, el animal que toc\u00f3 el domo de manera sumamente suave antes de elevarse hacia el arrecife para que la limpiaran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer buceo del d\u00eda siguiente fue en un canal con una fuerte corriente que lo atravesaba. Durante el informe de seguridad el divemaster nos inform\u00f3 que nos lanzar\u00edamos a un promontorio rocoso que se proyectaba hacia el mar abierto y, con la corriente entrante azotando, deber\u00edamos usar nuestros ganchos de arrecife para sujetarnos a un trozo de roca y esperar a que los tiburones se nos acercaran. El truco era que esto era a 27 metros (90 pies), por lo que no tendr\u00eda demasiado tiempo, e implicaba que un tibur\u00f3n de arrecife gris podr\u00eda acercarse a solo 1,5 o 1,8 metros (5 o 6 pies) como mucho. Tendr\u00eda suerte si pudiera experimentar algo m\u00e1s que una pasada distante. Esto no me permitir\u00eda obtener una foto de un tibur\u00f3n de clase mundial, por lo que me separ\u00e9 del arrecife y me desplac\u00e9 a la deriva por el canal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un buceo extremo en un canal era suficiente para m\u00ed. Cuando lleg\u00f3 el momento del siguiente buceo, quise conocer las opciones y le consult\u00e9 a la tripulaci\u00f3n sobre lo que desde la superficie se ve\u00eda como un arrecife inclinado. Era un lugar aleatorio en el que rara vez hab\u00edan buceado, pero por un arrecife saludable y coloridos peces tropicales de arrecife, result\u00f3 ser uno de los mejores buceos del viaje. El pez ballesta payaso ubicuo tambi\u00e9n estaba aqu\u00ed, pero como el arrecife era tan inmaculado, los fondos eran incre\u00edbles. Tuve una gran serie de fotos con majestuosos peces \u00e1ngel muy accesibles antes de continuar con un pez mariposa de nariz larga que estaba haciendo lo que su forma anat\u00f3mica le mandaba: hurgar dentro de diminutas fisuras de coral para alimentarse.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-style-large is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><span style=\"color: #005274;\" class=\"stk-highlight\">El pa\u00eds es tan vasto en lo que se refiere a atracciones marinas que es imposible equivocarse sin importar d\u00f3nde navegue su embarcaci\u00f3n de vida a bordo. El archipi\u00e9lago abarca casi 90.649 kil\u00f3metros cuadrados (35.000 millas cuadradas), y se extiende m\u00e1s de 820,8 kil\u00f3metros (510 millas) de norte a sur y 128,7 kil\u00f3metros (80 millas) de este a oeste.<\/span><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Esa noche tuvimos el placer de disfrutar de uno de los puntos m\u00e1s destacados de una aventura en las Maldivas \u2014un tibur\u00f3n ballena de noche\u2014. Los tiburones ballena son un plato fuerte de South Ari Atoll, particularmente durante la \u00e9poca de monzones en el noreste, que se extiende de diciembre a mayo. A medida que se acercaba el atardecer, la tripulaci\u00f3n encendi\u00f3 una potente luz hal\u00f3gena de cuarzo instalada en la plataforma de ba\u00f1o en la popa de la embarcaci\u00f3n. La luz atra\u00eda diminutos camarones y plancton mientras el crep\u00fasculo daba paso a la oscuridad. Tal como predijo la tripulaci\u00f3n, un joven tibur\u00f3n ballena vino a cenar. Med\u00eda quiz\u00e1s 5,5 metros (18 pies) y definitivamente no se ir\u00eda a ninguna otra parte mientras se sirviera comida. Ten\u00edamos todo el tiempo que quisi\u00e9ramos para hacer snorkel con el tibur\u00f3n ballena. Horas m\u00e1s tarde nos fuimos a la cama con el tibur\u00f3n ballena a\u00fan en la popa. No s\u00e9 qu\u00e9 sucedi\u00f3 cuando apagaron la luz, pero supongo que la cadena alimentaria se rompi\u00f3 r\u00e1pidamente, y ese fue el final hasta la visita de la noche siguiente desde otra embarcaci\u00f3n de vida a bordo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la ma\u00f1ana siguiente visitamos otra estaci\u00f3n de limpieza de mantas en&nbsp;<strong>Punto de Manta Kurali.&nbsp;<\/strong>Douglas Seifert inform\u00f3 en un art\u00edculo de 2018 en la revista&nbsp;<em>Inmersi\u00f3n&nbsp;<\/em>magazine<em>&nbsp;<\/em>las<strong>&nbsp;<\/strong>Maldivas son el hogar de \u201cla poblaci\u00f3n de rayas de arrecife m\u00e1s grande del mundo. Se dice que la poblaci\u00f3n total aproximada de mantarrayas en las Maldivas alcanza los 10.000 individuos; algunos creen que la cifra podr\u00eda ser el doble\u201d. Eso fue hace cuatro a\u00f1os, pero no vi nada que negara esa afirmaci\u00f3n. Este buceo tambi\u00e9n fue productivo, con todo el grupo siguiendo la indicaci\u00f3n de quedarse en una posici\u00f3n, y nuestra recompensa fue un grupo de tranquilas mantas felices de estar en las cercan\u00edas y que las limpiaran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros puntos memorables del viaje incluyen el inmaculado jard\u00edn superficial de coral duro en&nbsp;<strong>Hakura Thila<\/strong>&nbsp;y el banco de peces mariposa de cola roja en&nbsp;<strong>Vanhuravalhi Kandu<\/strong>Para este momento del viaje observ\u00e9 una curiosa escasez de coral blando, y para quitarnos esa sensaci\u00f3n nuestro personal de buceo sugiri\u00f3 visitar&nbsp;<strong>Fohtheyo Kandu<\/strong>Fue mejor en ese sentido que algunos de los arrecifes principalmente de coral duro donde hab\u00edamos buceado a principios de la semana, pero no est\u00e1bamos viendo nada que se comparara con Fiyi, Raja Ampat o el mar Rojo en lo que se refiere a coral blando. No dudo de que algunas partes de las Maldivas tienen m\u00e1s coral blando del que vimos, pero en general no fue una parte importante de nuestro itinerario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los mejores buceos del viaje tuvo lugar en la \u00faltima ma\u00f1ana. Algunos miembros de nuestro grupo eligieron no hacerlo para liberar gases, si bien ten\u00edamos m\u00e1s de 24 horas entre el buceo y nuestro vuelo. Hab\u00edamos regresado a anclar cerca de Mal\u00e9, y hay un punto de buceo llamado&nbsp;<strong>Pecera<\/strong>&nbsp;que se origin\u00f3 con restaurantes locales que desechaban sus cad\u00e1veres de peces cerca del muelle. A medida que el punto de buceo evolucion\u00f3 hasta transformarse en un sitio productivo, las embarcaciones de buceo y snorkel locales con frecuencia echaban cebo al agua como una provocaci\u00f3n a los peces. Los beneficiarios m\u00e1s evidentes de esta generosidad son las morenas. Hay innumerables morenas en recovecos y grietas a lo largo del fondo, y es com\u00fan ver dos o tres especies de anguilas cohabitando en un solo recoveco del arrecife. El lugar era tan bueno que buce\u00e9 all\u00ed dos veces, una con un objetivo gran angular de 16-35 mm para capturar un gran banco de \u00eddolos moros y modelos posando delante de inmensas morenas de puntos negros y m\u00e1s tarde con una lente macro de 50 mm para aprovechar todos los retratos de peces sencillos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, hay 33 \u00e1reas marinas protegidas por todas las Maldivas, una indicaci\u00f3n de que el gobierno es consciente del valor del arrecife de coral y que su importante megafauna (tiburones ballena, mantarrayas y tiburones) contribuye a la econom\u00eda nacional al atraer el turismo de buceo. Es posible que no puedan hacer demasiado para influir en el cambio clim\u00e1tico y el crecimiento del nivel del mar. Aun as\u00ed, pueden mejorar la calidad de sus recursos marinos, y el gobierno y la industria del buceo de las Maldivas est\u00e1n comprometidos a lograrlo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/istock-547405524-cropped.jpeg\" alt=\"mapa de Maldivas\" class=\"wp-image-22879\" width=\"307\" height=\"539\"\/><figcaption class=\"wp-element-caption\">Marca roja en un mapa, apuntando a la isla Maldivas<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">C\u00f3mo bucear en este lugar<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Temporada de buceo:<\/span><\/strong>&nbsp;la principal temporada de buceo es de diciembre a mayo, aunque hoy en d\u00eda se puede bucear pr\u00e1cticamente todo el a\u00f1o. Un monz\u00f3n del noreste llega hacia fines de diciembre y trae aguas m\u00e1s tranquilas a la mayor parte del archipi\u00e9lago. Con las condiciones m\u00e1s claras, se puede tener una visibilidad de m\u00e1s de 30 metros (100 pies), pero los movimientos de la marea pueden reducirla. Las mareas entrantes traen aguas cristalinas, pero las mareas salientes transportan sedimentos de la laguna y, a veces, disminuyen la visibilidad en el arrecife perif\u00e9rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Buceo con dhoni:<\/span><\/strong>&nbsp;la mayor\u00eda de las embarcaciones de vida a bordo operan sin\u00e9rgicamente con un dhoni \u2014un yate de 15 a 18 metros (50 a 60 pies) con motores di\u00e9sel y un compresor a bordo (habitualmente para aire y Nitrox)\u2014. Los visitantes duermen y cenan en la embarcaci\u00f3n madre, pero el buceo se realiza desde el dhoni. Esto a\u00edsla el ruido de la estaci\u00f3n de llenado del dhoni, que tambi\u00e9n tiene una plataforma estable con una escalera resistente para volver a subir a la embarcaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Corrientes:<\/span><\/strong>&nbsp;bucear en corrientes es una realidad en las Maldivas, aunque el personal de buceo puede elegir arrecifes que no tengan corrientes u optar por desplazarse a la deriva a toda velocidad a trav\u00e9s de los pasajes. Es posible salir a la superficie lejos del dhoni, por lo que cada buzo debe viajar con una boya de superficie de acci\u00f3n retardada y estar capacitado para usarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Profundidad:<\/span><\/strong>&nbsp;las leyes de las Maldivas restringen los buceos a los 30 metros (98 pies). No hay motivos para descender a mayores profundidades, dada la topograf\u00eda de los arrecifes y pasajes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Temperatura:<\/span><\/strong>&nbsp;se puede esperar temperaturas del aire entre 26,6 \u00b0C y 31,6 \u00b0C (81 \u00b0F y 89 \u00b0F) y temperaturas del agua de 26,6 \u00b0C a 30 \u00b0C (80 \u00b0F a 86 \u00b0F). He comprobado que un traje de neopreno de 3 mm es c\u00f3modo todo el a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Pasaportes y documentaci\u00f3n:<\/span><\/strong>&nbsp;consulte la informaci\u00f3n actual sobre pasaportes y requisitos de ingreso en&nbsp;<em>travel.state.gov\/content\/travel\/en\/international-travel\/International-Travel-Country-Information-Pages\/Maldives.html<\/em>Las restricciones de viaje actuales y las pol\u00edticas de COVID-19 est\u00e1n disponibles en&nbsp;<em>visitmaldives.com\/es\/covid19-updates<\/em>.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">EXPLORE M\u00c1S<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Vea m\u00e1s de las maravillosas Maldivas en una galer\u00eda de fotos adicional y en este video.<\/em><\/p>\n\n\n\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a579b2a334aa\" class=\"master-slider-parent ms-partialview-template ms-parent-id-28\" style=\"max-width:1000px;\" >\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a579b2a334aa\" class=\"master-slider ms-skin-light-3\" >\n\t\t\t\t \t\t\t\t \n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"1_Frink_Maldives_Feb_2016_176\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/1_Frink_Maldives_Feb_2016_176-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"2_Maldives_UW_1293-Edit\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/2_Maldives_UW_1293-Edit-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"3_F36B485\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/3_F36B485-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"4_Frink_Maldives_Feb_2016_055\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/4_Frink_Maldives_Feb_2016_055-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"5_Frink_Maldives_Feb_2016_633\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/5_Frink_Maldives_Feb_2016_633-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"6_Frink_Maldives_Feb_2016_445-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/6_Frink_Maldives_Feb_2016_445-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"7_Frink_Maldives_Feb_2016_1503\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/7_Frink_Maldives_Feb_2016_1503-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"8_Frink_Maldives_Feb_2016_1091-Edit-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/8_Frink_Maldives_Feb_2016_1091-Edit-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"9_Frink_Maldives_Feb_2016_916-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/9_Frink_Maldives_Feb_2016_916-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"10_Frink_Maldives_Feb_2016_1020-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/10_Frink_Maldives_Feb_2016_1020-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"11_Maldives_UW_167-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/11_Maldives_UW_167-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"12_Maldivas_UW_967\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/12_Maldives_UW_967-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"13_Maldivas_UW_1232\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/13_Maldives_UW_1232-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"14_Maldives_UW_1486-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/14_Maldives_UW_1486-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"15_Maldivas_UW_424\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/15_Maldives_UW_424-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"16_Maldives_2022_Top_116\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/16_Maldives_2022_Top_116-2.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"17_Maldives_UW_1306-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/17_Maldives_UW_1306-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"18_Frink_Maldives_Feb_2016_271-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/18_Frink_Maldives_Feb_2016_271-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"19_Frink_Maldives_Feb_2016_728-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/19_Frink_Maldives_Feb_2016_728-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"20_Frink_Maldives_Feb_2016_887-Edit-alt\" data-src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/03\/20_Frink_Maldives_Feb_2016_887-Edit-alt-1.jpg\" \/>\n\n\t\t\t\t\t<div class=\"ms-info ms-info-empty\">&nbsp;<\/div>\n\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t( window.MSReady = window.MSReady || [] ).push( function( $ ) {\n\n\t\t\t\"use strict\";\n\t\t\tvar masterslider_34aa = new MasterSlider();\n\n\t\t\t\/\/ slider controls\n\t\t\tmasterslider_34aa.control('arrows'     ,{ autohide:true, overVideo:true  });\n\t\t\tmasterslider_34aa.control('circletimer',{ autohide:false, overVideo:true, color:'#FFFFFF', radius:4, stroke:9   });\n\t\t\tmasterslider_34aa.control('slideinfo'  ,{ autohide:false, overVideo:true, dir:'h', align:'bottom',inset:false , margin:10   });\n\t\t\t\/\/ slider setup\n\t\t\tmasterslider_34aa.setup(\"MS6a579b2a334aa\", {\n\t\t\t\twidth           : 1000,\n\t\t\t\theight          : 667,\n\t\t\t\tminHeight       : 0,\n\t\t\t\tspace           : 10,\n\t\t\t\tstart           : 1,\n\t\t\t\tgrabCursor      : true,\n\t\t\t\tswipe           : true,\n\t\t\t\tmouse           : true,\n\t\t\t\tkeyboard        : false,\n\t\t\t\tlayout          : \"partialview\",\n\t\t\t\twheel           : false,\n\t\t\t\tautoplay        : true,\n                instantStartLayers:false,\n\t\t\t\tmobileBGVideo:false,\n\t\t\t\tloop            : true,\n\t\t\t\tshuffle         : false,\n\t\t\t\tpreload         : 0,\n\t\t\t\theightLimit     : true,\n\t\t\t\tautoHeight      : false,\n\t\t\t\tsmoothHeight    : true,\n\t\t\t\tendPause        : false,\n\t\t\t\toverPause       : true,\n\t\t\t\tfillMode        : \"fill\",\n\t\t\t\tcenterControls  : false,\n\t\t\t\tstartOnAppear   : false,\n\t\t\t\tlayersMode      : \"center\",\n\t\t\t\tautofillTarget  : \"\",\n\t\t\t\thideLayers      : false,\n\t\t\t\tfullscreenMargin: 0,\n\t\t\t\tspeed           : 20,\n\t\t\t\tdir             : \"h\",\n\t\t\t\tresponsive      : true,\n\t\t\t\ttabletWidth     : 768,\n\t\t\t\ttabletHeight    : null,\n\t\t\t\tphoneWidth      : 480,\n\t\t\t\tphoneHeight    : null,\n\t\t\t\tsizingReference : window,\n\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\tview            : \"fadeFlow\"\n\t\t\t});\n\n\t\t\t\n\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\twindow.masterslider_instances.push( masterslider_34aa );\n\t\t});\n\t\t<\/script>\n\n\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Presentaci\u00f3n de las Maldivas\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/GIimOIZy-RA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>WHILE THE WORLD WAS STILL MOSTLY LOCKED DOWN with travel restrictions, my social media feed was alive with gorgeous photos from the Maldives. The Maldives opened sooner than most foreign dive destinations, so there was ample photographic inspiration for our trip in May. The online coverage included the whale sharks, manta rays, tiger sharks, and [\u2026]<\/p>\n","protected":false},"featured_media":22871,"template":"","dan_alert_diver_categories":[73],"dan_alert_diver_issues":[481],"class_list":["post-22869","dan_alert_diver","type-dan_alert_diver","status-publish","has-post-thumbnail","hentry","dan_alert_diver_categories-features","dan_alert_diver_issues-q3-2022"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Maldives - DAN World<\/title>\n<meta name=\"description\" content=\"WHILE THE WORLD WAS STILL MOSTLY LOCKED DOWN\u00a0with travel restrictions, my social media feed was alive with gorgeous photos from the Maldives.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-maldives\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Maldives\" \/>\n<meta property=\"og:description\" content=\"WHILE THE WORLD WAS STILL MOSTLY LOCKED DOWN\u00a0with travel restrictions, my social media feed was alive with gorgeous photos from the Maldives.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-maldives\/\" \/>\n<meta property=\"og:site_name\" content=\"DAN World\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T20:54:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_76_maldives-e1660323606717.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1077\" \/>\n\t<meta property=\"og:image:height\" content=\"564\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"WHILE THE WORLD WAS STILL MOSTLY LOCKED DOWN\u00a0with travel restrictions, my social media feed was alive with gorgeous photos from the Maldives.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/id\\\/alert-diver\\\/article\\\/the-maldives\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/id\\\/alert-diver\\\/article\\\/the-maldives\\\/\",\"name\":\"The Maldives - DAN World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/id\\\/alert-diver\\\/article\\\/the-maldives\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/id\\\/alert-diver\\\/article\\\/the-maldives\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/q3_76_maldives-e1660323606717.jpeg\",\"datePublished\":\"2022-08-25T15:13:30+00:00\",\"dateModified\":\"2023-02-08T20:54:50+00:00\",\"description\":\"WHILE THE WORLD WAS STILL MOSTLY LOCKED DOWN\u00a0with travel restrictions, my social media feed was alive with gorgeous photos from the Maldives.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/id\\\/alert-diver\\\/article\\\/the-maldives\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/world.dan.org\\\/id\\\/alert-diver\\\/article\\\/the-maldives\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/id\\\/alert-diver\\\/article\\\/the-maldives\\\/#primaryimage\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/q3_76_maldives-e1660323606717.jpeg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/q3_76_maldives-e1660323606717.jpeg\",\"width\":1077,\"height\":564,\"caption\":\"Maldives Aggressor II, April 2022. Manta cleaning station at North Ari Atoll. Dangahi cleaning station.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/id\\\/alert-diver\\\/article\\\/the-maldives\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/world.dan.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Maldives\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"name\":\"DAN World\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/world.dan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\",\"name\":\"DAN World\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"width\":175,\"height\":52,\"caption\":\"DAN World\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las Maldivas - DAN World","description":"MIENTRAS EL MUNDO SIGU\u00cdA CERRADO A LAS RESTRICCIONES DE VIAJE, mis redes sociales estaban llenas de fotos preciosas de las Maldivas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-maldives\/","og_locale":"es_MX","og_type":"article","og_title":"The Maldives","og_description":"WHILE THE WORLD WAS STILL MOSTLY LOCKED DOWN\u00a0with travel restrictions, my social media feed was alive with gorgeous photos from the Maldives.","og_url":"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-maldives\/","og_site_name":"DAN World","article_modified_time":"2023-02-08T20:54:50+00:00","og_image":[{"width":1077,"height":564,"url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_76_maldives-e1660323606717.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"WHILE THE WORLD WAS STILL MOSTLY LOCKED DOWN\u00a0with travel restrictions, my social media feed was alive with gorgeous photos from the Maldives.","twitter_misc":{"Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/world.dan.org\/id\/alert-diver\/article\/the-maldives\/","url":"https:\/\/world.dan.org\/id\/alert-diver\/article\/the-maldives\/","name":"Las Maldivas - DAN World","isPartOf":{"@id":"https:\/\/world.dan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/world.dan.org\/id\/alert-diver\/article\/the-maldives\/#primaryimage"},"image":{"@id":"https:\/\/world.dan.org\/id\/alert-diver\/article\/the-maldives\/#primaryimage"},"thumbnailUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_76_maldives-e1660323606717.jpeg","datePublished":"2022-08-25T15:13:30+00:00","dateModified":"2023-02-08T20:54:50+00:00","description":"MIENTRAS EL MUNDO SIGU\u00cdA CERRADO A LAS RESTRICCIONES DE VIAJE, mis redes sociales estaban llenas de fotos preciosas de las Maldivas.","breadcrumb":{"@id":"https:\/\/world.dan.org\/id\/alert-diver\/article\/the-maldives\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/world.dan.org\/id\/alert-diver\/article\/the-maldives\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/id\/alert-diver\/article\/the-maldives\/#primaryimage","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_76_maldives-e1660323606717.jpeg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/08\/q3_76_maldives-e1660323606717.jpeg","width":1077,"height":564,"caption":"Maldives Aggressor II, April 2022. Manta cleaning station at North Ari Atoll. Dangahi cleaning station."},{"@type":"BreadcrumbList","@id":"https:\/\/world.dan.org\/id\/alert-diver\/article\/the-maldives\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/world.dan.org\/"},{"@type":"ListItem","position":2,"name":"The Maldives"}]},{"@type":"WebSite","@id":"https:\/\/world.dan.org\/es\/#website","url":"https:\/\/world.dan.org\/es\/","name":"DAN World","description":"","publisher":{"@id":"https:\/\/world.dan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/world.dan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/world.dan.org\/es\/#organization","name":"DAN World","url":"https:\/\/world.dan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","width":175,"height":52,"caption":"DAN World"},"image":{"@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver\/22869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver"}],"about":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/types\/dan_alert_diver"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media\/22871"}],"wp:attachment":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media?parent=22869"}],"wp:term":[{"taxonomy":"dan_alert_diver_categories","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_categories?post=22869"},{"taxonomy":"dan_alert_diver_issues","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_issues?post=22869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}