{"id":23465,"date":"2022-11-28T16:12:58","date_gmt":"2022-11-28T21:12:58","guid":{"rendered":"https:\/\/world.dan.org\/?post_type=dan_alert_diver&#038;p=23465"},"modified":"2023-01-30T12:08:32","modified_gmt":"2023-01-30T17:08:32","slug":"practice-crucial-skills","status":"publish","type":"dan_alert_diver","link":"https:\/\/world.dan.org\/es\/alert-diver\/article\/practice-crucial-skills\/","title":{"rendered":"Pr\u00e1ctica de habilidades cruciales"},"content":{"rendered":"<p class=\"has-medium-font-size wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">TRABAJAR COMO PRIMER OFICIAL EN EMBARCACIONES<\/span><\/strong>&nbsp;de buceo por los \u00faltimos 22 a\u00f1os me ha dado la posibilidad de ser parte de muchas situaciones interesantes. Al dictar clases de buceo con aire comprimido, utilizo una situaci\u00f3n en particular como evidencia de la importancia de mantener las habilidades a trav\u00e9s de una pr\u00e1ctica regular. Ilustra que el buceo no admite ning\u00fan tipo de complacencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00eda hab\u00eda comenzado sin problemas con los pasajeros abordando el buque y haciendo los preparativos necesarios para bucear. Zarpamos y nos dirigimos a un naufragio de la Segunda Guerra Mundial que yace en aguas superficiales \u2014a aproximadamente 20 metros de profundidad\u2014 cerca de la costa de Carolina del Norte. Por lo general, la visibilidad es de 6 a 9 metros. Los operadores de buceo comercial normalmente no visitan el naufragio debido a su peque\u00f1o tama\u00f1o y la posibilidad de que la visibilidad sea limitada. Todos los buzos a bordo hab\u00edan estado en el barco anteriormente y estaban familiarizados con la tripulaci\u00f3n, la embarcaci\u00f3n y el naufragio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese d\u00eda era mi turno de asegurar el ancla mientras otro miembro de la tripulaci\u00f3n ayudaba al capit\u00e1n para hacer ingresar a los buzos al agua. Despu\u00e9s de que el capit\u00e1n maniobr\u00f3 la embarcaci\u00f3n para ubicarla sobre el punto, me dio le se\u00f1al para que actuara, y me lanc\u00e9 desde la cubierta con el ancla en la mano. Durante el breve descenso advert\u00ed que la visibilidad era de 4 a 6 metros, completamente dentro de las expectativas para el punto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que asegur\u00e9 el ancla al naufragio, transmit\u00ed la ubicaci\u00f3n de anclaje y las condiciones de buceo a la superficie a trav\u00e9s de un sistema de comunicaci\u00f3n inal\u00e1mbrico. Adem\u00e1s de informar la visibilidad, le avis\u00e9 al capit\u00e1n que hab\u00eda una corriente m\u00ednima y no hab\u00eda oleaje. Despu\u00e9s de cumplir con esa parte de mis obligaciones, estuve libre para explorar el naufragio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el buceo encontr\u00e9 a varios de nuestros pasajeros disfrutando de su propia experiencia. Debido a la huella de carbono relativamente peque\u00f1a del naufragio, ser\u00eda bastante inusual que una segunda embarcaci\u00f3n anclara en el punto. A medida que mi l\u00edmite de no descompresi\u00f3n se acercaba, me dirig\u00ed a la ubicaci\u00f3n de anclaje y me prepar\u00e9 para iniciar mi ascenso. Cuando me ocupo del anclaje, habitualmente hago una pausa en mi ascenso para verificar el estado de los otros buzos. S\u00e9 cu\u00e1l ser\u00e1 su tiempo de buceo aproximado, y puedo darme cuenta, por el rastro de sus burbujas, de si alguno de ellos se est\u00e1 acercando al ancla o ha iniciado su ascenso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al detenerme a los 9 metros, observ\u00e9 que dos buzos estaban ascendiendo por la l\u00ednea de anclaje y se acercaban r\u00e1pidamente a mi posici\u00f3n. En cuanto pude verlos fue evidente que estaban enfrent\u00e1ndose a una situaci\u00f3n donde se estaban quedando sin aire. Era un equipo de padre e hijo, y el padre estaba compartiendo su octopus con el hijo. Ambos buzos respiraban con dificultad y se mov\u00edan con determinaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Descend\u00ed inmediatamente y establec\u00ed contacto con el equipo de compa\u00f1eros. En ese momento el suministro de gas del dador se agot\u00f3. Est\u00e1bamos a unos 12 metros bajo el agua, y ten\u00eda a dos buzos que necesitaban gas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabiendo que el padre ten\u00eda m\u00e1s experiencia, le ofrec\u00ed mi octopus al hijo y respir\u00e9 una vez a trav\u00e9s de mi segunda etapa principal. Con las manos ocupadas sosteniendo al equipo de buzos y mi regulador principal, no pod\u00eda hacer una se\u00f1al para comunicarle mis intenciones al padre. \u00c9l se dio cuenta de que su hijo estaba respirando a trav\u00e9s de mi octopus y que yo estaba listo para compartir mi regulador principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de quitarse su ya in\u00fatil regulador, se coloc\u00f3 mi segunda etapa principal y respir\u00f3 por primera vez a trav\u00e9s de mi equipo. Mientras yo continuaba exhalando, le permit\u00ed al padre respirar varias veces m\u00e1s antes de darle un peque\u00f1o tir\u00f3n a mi regulador principal. Despu\u00e9s de respirar otra vez, el padre me permiti\u00f3 recuperar mi segunda etapa moment\u00e1neamente para respirar dos veces. R\u00e1pidamente establecimos un ritmo de dos respiraciones cada uno para un uso compartido del regulador a la vez que manten\u00eda un contacto con el hijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que nuestro ciclo de respiraci\u00f3n se normaliz\u00f3, control\u00e9 mi suministro de gas. Buceo con tanques que son m\u00e1s grandes que lo que necesito en caso de que se produzcan situaciones como esta. Los tanques de 15 litros eran mucho m\u00e1s que suficiente para suministrarnos gas, incluso despu\u00e9s de haber hecho un buceo de no descompresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando ambos buzos estuvieron c\u00f3modos y respirando normalmente, ten\u00eda que llevarlos desde nuestra posici\u00f3n actual hasta la l\u00ednea de descompresi\u00f3n (hang line) y los \u201creguladores suspendidos en la l\u00ednea de descompresi\u00f3n\u201d (hang regulators), que se utilizan en situaciones donde un buzo tiene poco o nada de gas y a\u00fan debe realizar una parada de seguridad o de descompresi\u00f3n. La primera etapa est\u00e1 sujeta a un tanque a bordo de la embarcaci\u00f3n con la segunda etapa en el extremo de una manguera de baja presi\u00f3n de 9 metros con peso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos buzos me devolvieron la se\u00f1a con el pulgar hacia arriba, y comenzamos a ascender nuevamente. El hijo continu\u00f3 respirando a trav\u00e9s de mi octopus, mientras el padre y yo manten\u00edamos la secuencia de uso compartido del regulador de dos respiraciones cada uno. Llegamos al lugar donde estaba el peso y nos desplazamos hacia los reguladores suspendidos en la l\u00ednea de descompresi\u00f3n en la popa. La embarcaci\u00f3n estaba configurada con un regulador suspendido a cada lado, por lo que los buzos soltaron mi segunda etapa y comenzaron a respirar a trav\u00e9s de los reguladores suspendidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras terminaban su parada de seguridad de emergencia, yo mantuve una posici\u00f3n que me permit\u00eda mantener contacto visual con ellos y estar lo suficientemente cerca para intervenir si era necesario. Los buzos finalizaron su parada sin m\u00e1s incidentes y pudieron subir a la embarcaci\u00f3n. En cuanto el equipo de compa\u00f1eros estuvo a bordo, sal\u00ed del agua y me prepar\u00e9 para recibir a los pasajeros restantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No s\u00e9 cu\u00e1les fueron las circunstancias que hicieron que estos buzos se quedaran sin gas durante el buceo, pero la lecci\u00f3n es que es fundamental monitorear los medidores \u2014una lecci\u00f3n qu\u00e9 todos los buzos deben tener en cuenta\u2014. Saber c\u00f3mo compartir gas, como dador y como receptor, mediante el uso de una t\u00e9cnica diferente al uso compartido de una fuente de aire alternativa tambi\u00e9n es fundamental. Si el padre no hubiera estado capacitado ni preparado para el uso compartido del regulador, el resultado podr\u00eda haber sido desastroso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reciba capacitaci\u00f3n, practique la capacitaci\u00f3n recibida y piense con originalidad sobre c\u00f3mo incorporar su capacitaci\u00f3n a diferentes situaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a9&nbsp;<em>Alert Diver<\/em>&nbsp;- Q4 2022<\/p>","protected":false},"excerpt":{"rendered":"<p>TRABAJAR COMO PRIMER OFICIAL EN EMBARCACIONES de buceo por los \u00faltimos 22 a\u00f1os me ha dado la posibilidad de ser parte de muchas situaciones interesantes. Al dictar clases de buceo con aire comprimido, utilizo una situaci\u00f3n en particular como evidencia de la importancia de mantener las habilidades a trav\u00e9s de una pr\u00e1ctica regular. Ilustra que el buceo no admite ning\u00fan tipo de complacencia. [...]<\/p>","protected":false},"featured_media":23466,"template":"","dan_alert_diver_categories":[84],"dan_alert_diver_issues":[482],"class_list":["post-23465","dan_alert_diver","type-dan_alert_diver","status-publish","has-post-thumbnail","hentry","dan_alert_diver_categories-skills-in-action","dan_alert_diver_issues-q4-2022"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Practice Crucial Skills - DAN World<\/title>\n<meta name=\"description\" content=\"When teaching scuba classes, I use one particular situation as evidence of the importance of maintaining skills through regular practice.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/practice-crucial-skills\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Practice Crucial Skills\" \/>\n<meta property=\"og:description\" content=\"When teaching scuba classes, I use one particular situation as evidence of the importance of maintaining skills through regular practice.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/practice-crucial-skills\/\" \/>\n<meta property=\"og:site_name\" content=\"DAN World\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-30T17:08:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/11\/alert-diver-q4-2022_102_skills-in-action.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"648\" \/>\n\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"When teaching scuba classes, I use one particular situation as evidence of the importance of maintaining skills through regular practice.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/practice-crucial-skills\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/practice-crucial-skills\\\/\",\"name\":\"Practice Crucial Skills - DAN World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/practice-crucial-skills\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/practice-crucial-skills\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/alert-diver-q4-2022_102_skills-in-action.jpeg\",\"datePublished\":\"2022-11-28T21:12:58+00:00\",\"dateModified\":\"2023-01-30T17:08:32+00:00\",\"description\":\"When teaching scuba classes, I use one particular situation as evidence of the importance of maintaining skills through regular practice.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/practice-crucial-skills\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/practice-crucial-skills\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/practice-crucial-skills\\\/#primaryimage\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/alert-diver-q4-2022_102_skills-in-action.jpeg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/alert-diver-q4-2022_102_skills-in-action.jpeg\",\"width\":648,\"height\":457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/practice-crucial-skills\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/world.dan.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Practice Crucial Skills\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"name\":\"DAN World\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/world.dan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\",\"name\":\"DAN World\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"width\":175,\"height\":52,\"caption\":\"DAN World\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Practica habilidades cruciales - DAN World","description":"Cuando imparto clases de submarinismo, utilizo una situaci\u00f3n concreta como prueba de la importancia de mantener las destrezas mediante la pr\u00e1ctica regular.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/world.dan.org\/es\/alert-diver\/article\/practice-crucial-skills\/","og_locale":"es_MX","og_type":"article","og_title":"Practice Crucial Skills","og_description":"When teaching scuba classes, I use one particular situation as evidence of the importance of maintaining skills through regular practice.","og_url":"https:\/\/world.dan.org\/es\/alert-diver\/article\/practice-crucial-skills\/","og_site_name":"DAN World","article_modified_time":"2023-01-30T17:08:32+00:00","og_image":[{"width":648,"height":457,"url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/11\/alert-diver-q4-2022_102_skills-in-action.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"When teaching scuba classes, I use one particular situation as evidence of the importance of maintaining skills through regular practice.","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/world.dan.org\/alert-diver\/article\/practice-crucial-skills\/","url":"https:\/\/world.dan.org\/alert-diver\/article\/practice-crucial-skills\/","name":"Practica habilidades cruciales - DAN World","isPartOf":{"@id":"https:\/\/world.dan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/practice-crucial-skills\/#primaryimage"},"image":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/practice-crucial-skills\/#primaryimage"},"thumbnailUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/11\/alert-diver-q4-2022_102_skills-in-action.jpeg","datePublished":"2022-11-28T21:12:58+00:00","dateModified":"2023-01-30T17:08:32+00:00","description":"Cuando imparto clases de submarinismo, utilizo una situaci\u00f3n concreta como prueba de la importancia de mantener las destrezas mediante la pr\u00e1ctica regular.","breadcrumb":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/practice-crucial-skills\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/world.dan.org\/alert-diver\/article\/practice-crucial-skills\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/alert-diver\/article\/practice-crucial-skills\/#primaryimage","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/11\/alert-diver-q4-2022_102_skills-in-action.jpeg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/11\/alert-diver-q4-2022_102_skills-in-action.jpeg","width":648,"height":457},{"@type":"BreadcrumbList","@id":"https:\/\/world.dan.org\/alert-diver\/article\/practice-crucial-skills\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/world.dan.org\/"},{"@type":"ListItem","position":2,"name":"Practice Crucial Skills"}]},{"@type":"WebSite","@id":"https:\/\/world.dan.org\/es\/#website","url":"https:\/\/world.dan.org\/es\/","name":"DAN World","description":"","publisher":{"@id":"https:\/\/world.dan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/world.dan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/world.dan.org\/es\/#organization","name":"DAN World","url":"https:\/\/world.dan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","width":175,"height":52,"caption":"DAN World"},"image":{"@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver\/23465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver"}],"about":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/types\/dan_alert_diver"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media\/23466"}],"wp:attachment":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media?parent=23465"}],"wp:term":[{"taxonomy":"dan_alert_diver_categories","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_categories?post=23465"},{"taxonomy":"dan_alert_diver_issues","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_issues?post=23465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}