{"id":24051,"date":"2023-03-27T15:10:59","date_gmt":"2023-03-27T19:10:59","guid":{"rendered":"https:\/\/world.dan.org\/?post_type=dan_alert_diver&#038;p=24051"},"modified":"2023-05-09T10:05:16","modified_gmt":"2023-05-09T14:05:16","slug":"the-dive-light-a-tool-for-all-divers","status":"publish","type":"dan_alert_diver","link":"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","title":{"rendered":"La luz de buceo: una herramienta para todos los buzos"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.addtoany.com\/share\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La luz de buceo es una pieza fundamental del equipo que puede beneficiar a todos los buzos en la mayor\u00eda de los buceos. Existen varios tipos de luces con diversos usos y algunas consideraciones clave que hay que tener en cuenta antes de realizar una compra. No hay un enfoque \u00fanico en cuanto a las luces de buceo, por lo que cada buzo debe considerar con cuidado sus propios objetivos y necesidades antes de decidir qu\u00e9 modelo le resulta m\u00e1s \u00fatil.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-dive-light-uses\">Usos de las luces de buceo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los buzos a menudo creen que las luces son \u00fanicamente para iluminar lo que yace debajo de la superficie en buceos nocturnos, pero esa es solo una de varias aplicaciones. En los buceos donde no hay luz ambiental (como sucede en el buceo nocturno o en cuevas), las luces de buceo iluminar\u00e1n sus alrededores, pero tambi\u00e9n puede usarlas para comunicarse con otros buzos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con luz ambiental, las luces de buceo pueden restablecer los colores que se pierden con la profundidad, ayudar a obtener fotos de alta calidad de vida submarina e iluminar a peque\u00f1as criaturas debajo de salientes o en grietas. Puede usar luces de buceo para comunicarse en estas condiciones, aunque sus se\u00f1ales probablemente sean m\u00e1s dif\u00edciles de ver.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una luz de buceo tambi\u00e9n puede ayudar a hacer se\u00f1ales para indicar que hay una emergencia tanto en la superficie como bajo el agua. Un movimiento r\u00e1pido hacia adelante y hacia atr\u00e1s bajo el agua indica que hay un buzo en problemas. En la superficie, una luz de buceo puede atraer la atenci\u00f3n de la embarcaci\u00f3n de buceo o un helic\u00f3ptero de rescate, suponiendo que las condiciones permitan que pueda verse desde lejos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los usos no tradicionales de las luces de buceo incluyen alumbrar una bandera de buceo que un buzo est\u00e9 arrastrando por la noche o iluminar un pabell\u00f3n para preparar el equipo despu\u00e9s de la puesta del sol. Un fabricante incluso alienta a los clientes a usar sus luces en torno a una parrilla exterior para disfrutar de bocadillos nocturnos despu\u00e9s de un buceo. No obstante, no todas las luces de buceo pueden funcionar de manera segura fuera del agua por per\u00edodos prolongados, por lo que los buzos deben investigar antes de usarlas de manera no tradicional.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tipos de luces de buceo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">luces manuales inal\u00e1mbricas que son f\u00e1ciles de transportar y de usar y que, habitualmente, tienen un precio razonable. Los buzos t\u00e9cnicos a menudo prefieren luces empotradas por sus tiempos de funcionamiento m\u00e1s prolongados y la capacidad de soltarlas sin perder el cabezal de la luz. Varios fabricantes han desarrollado luces inal\u00e1mbricas con especificaciones similares a las luces empotradas, as\u00ed que muchos buzos t\u00e9cnicos est\u00e1n haciendo el cambio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las luces LED (diodo emisor de luz) se est\u00e1n volviendo m\u00e1s populares debido a sus potentes haces, pero algunos buzos prefieren las luces HID (descarga de alta intensidad) con haces que funcionan bien en agua turbia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los buzos tambi\u00e9n deben considerar las opciones de montaje. Algunas personas usan un asa Goodman r\u00edgida o blanda, mientras otras utilizan una correa de mano. Tambi\u00e9n puede montar luces de buceo en un casco o la correa de una m\u00e1scara.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_51_gear.jpg\" alt=\"Los buceadores de cuevas a menudo optan por utilizar luces de bote\" class=\"wp-image-24054\" width=\"297\" height=\"445\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_51_gear.jpg 534w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_51_gear-240x360.jpg 240w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_51_gear-8x12.jpg 8w\" sizes=\"auto, (max-width: 297px) 100vw, 297px\" \/><figcaption class=\"wp-element-caption\">Los buceadores de cuevas suelen optar por las linternas de bombona por su mayor autonom\u00eda.\n\u00a9NATALIE L. GIBB<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear.jpg\" alt=\"Varias luces en el mercado actual\" class=\"wp-image-24055\" width=\"592\" height=\"333\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear.jpg 800w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear-360x203.jpg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear-768x432.jpg 768w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear-18x10.jpg 18w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><figcaption class=\"wp-element-caption\">Hoy en d\u00eda existen varias luces en el mercado que se adaptan a las necesidades de la mayor\u00eda de los submarinistas.\n\u00a9KYLE HABECKER<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Consideraciones antes de realizar una compra<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las luces de buceo de primera calidad son costosas, y los buzos deben informarse antes de adquirir una. La aplicaci\u00f3n prevista determina el tiempo de funcionamiento que necesitar\u00e1. Un buzo de cuevas, por ejemplo, necesita tiempos de funcionamiento m\u00e1s prolongados que un buzo de aguas abiertas que realiza buceos en arrecifes durante el d\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus necesidades y usos ayudar\u00e1n a determinar qu\u00e9 intensidad (medida en l\u00famenes) y cobertura (medida en lux o l\u00famenes por metro cuadrado) necesitar\u00e1 en el haz de la luz de buceo. El \u00e1ngulo del haz tambi\u00e9n es crucial para utilizar la luz para comunicarse. Cuanto m\u00e1s estrecho sea el haz, m\u00e1s f\u00e1cil ser\u00e1 discernir las se\u00f1ales. La visibilidad del haz es especialmente crucial en condiciones sin luz ambiental o en buceos t\u00e9cnicos que requieren una comunicaci\u00f3n del equipo clara y concisa.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante adquirir una luz de buceo de un fabricante reconocido. Sus productos tienen calidad y confiabilidad comprobadas, y es m\u00e1s sencillo obtener asistencia y reparaciones confiables a trav\u00e9s del servicio al cliente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Consejos y trucos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Independientemente de qu\u00e9 luz de buceo elija, algunos consejos pueden ayudar a que el buceo sea m\u00e1s seguro y placentero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debe realizar una prueba de funcionamiento con todas las luces de buceo cada seis a 12 meses. Encienda sus luces completamente cargadas y col\u00f3quelas en una cubeta con agua. Registre el tiempo que la bater\u00eda tarda en agotarse y monitoree cualquier cambio con respecto a pruebas anteriores. Las pruebas de funcionamiento ayudan a los buzos a identificar cu\u00e1ndo es el momento de reemplazar las pilas para optimizar el funcionamiento de las luces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los buzos deben hacer uso de un protocolo adecuado respecto a las luces mientras est\u00e9n en el agua. Mantenga el haz hacia adelante y lo m\u00e1s estable que sea posible. Mueva el haz lentamente y evite los movimientos err\u00e1ticos que otros puedan confundir con se\u00f1ales de emergencia. Preste atenci\u00f3n a d\u00f3nde apunte la luz para no dirigirla directamente a los ojos de otros buzos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El buzo principal de un grupo debe considerar atenuar su luz. Esta pr\u00e1ctica permite que las luces de los individuos que lo sigan sean m\u00e1s visibles, lo que mejora la comunicaci\u00f3n del equipo y permite bucear de manera m\u00e1s segura.&nbsp;<\/p>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">\u00a9&nbsp;<em>Alert Diver<\/em>&nbsp;- Q1 2023<\/p>","protected":false},"excerpt":{"rendered":"<p>La luz de buceo es una pieza fundamental del equipo que puede beneficiar a todos los buzos en la mayor\u00eda de los buceos. Existen varios tipos de luces con diversos usos y algunas consideraciones clave que hay que tener en cuenta antes de realizar una compra. No hay un enfoque \u00fanico en cuanto a las luces de buceo, por lo que cada buzo debe considerar con cuidado sus propios objetivos y necesidades antes de decidir qu\u00e9 modelo le resulta m\u00e1s \u00fatil.<\/p>","protected":false},"featured_media":24052,"template":"","dan_alert_diver_categories":[71],"dan_alert_diver_issues":[484],"class_list":["post-24051","dan_alert_diver","type-dan_alert_diver","status-publish","has-post-thumbnail","hentry","dan_alert_diver_categories-gear","dan_alert_diver_issues-q1-2023"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Dive Light: A Tool for All Divers - DAN World<\/title>\n<meta name=\"description\" content=\"The dive light is essential equipment that can benefit all divers on most dives. There are several types of lights with various uses and a few key considerations you should make before purchasing.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Dive Light: A Tool for All Divers\" \/>\n<meta property=\"og:description\" content=\"The dive light is essential equipment that can benefit all divers on most dives. There are several types of lights with various uses and a few key considerations you should make before purchasing.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/\" \/>\n<meta property=\"og:site_name\" content=\"DAN World\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-09T14:05:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"The dive light is essential equipment that can benefit all divers on most dives.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/\",\"name\":\"The Dive Light: A Tool for All Divers - DAN World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/q1_52_gear.jpg\",\"datePublished\":\"2023-03-27T19:10:59+00:00\",\"dateModified\":\"2023-05-09T14:05:16+00:00\",\"description\":\"The dive light is essential equipment that can benefit all divers on most dives. There are several types of lights with various uses and a few key considerations you should make before purchasing.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/q1_52_gear.jpg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/q1_52_gear.jpg\",\"width\":1200,\"height\":1132,\"caption\":\"Lights are tools for all divers, even when ambient light is present. \u00a9STEPHEN FRINK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/world.dan.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Dive Light: A Tool for All Divers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"name\":\"DAN World\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/world.dan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\",\"name\":\"DAN World\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"width\":175,\"height\":52,\"caption\":\"DAN World\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La linterna de buceo: Una herramienta para todos los buceadores - DAN World","description":"La linterna de buceo es un equipo esencial que puede beneficiar a todos los buceadores en la mayor\u00eda de las inmersiones. Existen varios tipos de linternas con distintos usos y algunas consideraciones clave que debes tener en cuenta antes de comprarlas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","og_locale":"es_MX","og_type":"article","og_title":"The Dive Light: A Tool for All Divers","og_description":"The dive light is essential equipment that can benefit all divers on most dives. There are several types of lights with various uses and a few key considerations you should make before purchasing.","og_url":"https:\/\/world.dan.org\/es\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","og_site_name":"DAN World","article_modified_time":"2023-05-09T14:05:16+00:00","og_image":[{"width":1200,"height":1132,"url":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"The dive light is essential equipment that can benefit all divers on most dives.","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","url":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","name":"La linterna de buceo: Una herramienta para todos los buceadores - DAN World","isPartOf":{"@id":"https:\/\/world.dan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#primaryimage"},"image":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#primaryimage"},"thumbnailUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg","datePublished":"2023-03-27T19:10:59+00:00","dateModified":"2023-05-09T14:05:16+00:00","description":"La linterna de buceo es un equipo esencial que puede beneficiar a todos los buceadores en la mayor\u00eda de las inmersiones. Existen varios tipos de linternas con distintos usos y algunas consideraciones clave que debes tener en cuenta antes de comprarlas.","breadcrumb":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#primaryimage","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg","width":1200,"height":1132,"caption":"Lights are tools for all divers, even when ambient light is present. \u00a9STEPHEN FRINK"},{"@type":"BreadcrumbList","@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/world.dan.org\/"},{"@type":"ListItem","position":2,"name":"The Dive Light: A Tool for All Divers"}]},{"@type":"WebSite","@id":"https:\/\/world.dan.org\/es\/#website","url":"https:\/\/world.dan.org\/es\/","name":"DAN World","description":"","publisher":{"@id":"https:\/\/world.dan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/world.dan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/world.dan.org\/es\/#organization","name":"DAN World","url":"https:\/\/world.dan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","width":175,"height":52,"caption":"DAN World"},"image":{"@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver\/24051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver"}],"about":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/types\/dan_alert_diver"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media\/24052"}],"wp:attachment":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media?parent=24051"}],"wp:term":[{"taxonomy":"dan_alert_diver_categories","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_categories?post=24051"},{"taxonomy":"dan_alert_diver_issues","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_issues?post=24051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}