{"id":25924,"date":"2023-12-11T16:31:31","date_gmt":"2023-12-11T21:31:31","guid":{"rendered":"https:\/\/world.dan.org\/?post_type=dan_alert_diver&#038;p=25924"},"modified":"2024-01-29T13:47:45","modified_gmt":"2024-01-29T18:47:45","slug":"slow-and-relaxed-with-good-technique","status":"publish","type":"dan_alert_diver","link":"https:\/\/world.dan.org\/es\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/","title":{"rendered":"Lento y relajado con una buena t\u00e9cnica"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>MI COMPA\u00d1ERO DE BUCEO Y YO <\/strong>ten\u00edamos previsto hacer un buceo m\u00e1s largo de lo habitual una ma\u00f1ana de s\u00e1bado en el parque estatal Madison Blue Spring State Park en Lee, Florida. Tras hacer m\u00e1s de 100 buceos en cuevas juntos durante varios a\u00f1os, hab\u00edamos acumulado experiencia como equipo y tiempo en este sistema de cuevas submarinas espec\u00edfico en el norte de Florida. Lentamente hab\u00edamos extendido la duraci\u00f3n y la distancia de nuestros buceos en este laberinto de t\u00faneles submarinos que se entrelazaban por la caliza c\u00e1rstica del parque, lo que nos permiti\u00f3 mejorar nuestra familiaridad con el sistema y a la vez practicar las habilidades que hab\u00edamos aprendido y segu\u00edamos desarrollando para ser buzos de cuevas prudentes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plan de buceo era nadar aproximadamente 1.067 metros (3.500 pies) hacia el interior del sistema y regresar cuando uno de nosotros hubiera agotado un tercio de nuestro suministro de gas. Nos colocamos el equipo y caminamos hacia el manantial, y observamos que el agua era transparente como el aire, al igual que muchos manantiales de agua dulce de Florida.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de realizar los controles del equipo anteriores al buceo y repasar el plan de buceo, nos sumergimos y nos dirigimos al sistema de cuevas. Nuestras luces rebotaban en las paredes de piedra caliza de color blanco brillante mientras nad\u00e1bamos por los t\u00faneles. A pesar de estar familiarizados con la cueva tras hacer docenas de buceos anteriormente, nos tomamos nuestro tiempo y prestamos atenci\u00f3n a sus detalles para permanecer conscientes de nuestro entorno.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como buzos de cuevas aprendemos una variedad de habilidades para situaciones de emergencia, incluso c\u00f3mo manejar la p\u00e9rdida de nuestra luz principal. Cada uno de nosotros lleva dos luces de repuesto, m\u00e1s peque\u00f1as y con un campo visual m\u00e1s estrecho. Tras recorrer aproximadamente 610 metros (2.000 pies) mi luz principal se apag\u00f3, por lo que inmediatamente busqu\u00e9 mi primera luz de repuesto. Si bien funcionaba cuando la prob\u00e9 como parte del control anterior al buceo, mi luz de repuesto no se encend\u00eda.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Mi compa\u00f1ero de buceo se dio cuenta de que mi haz de luz hab\u00eda desaparecido y permaneci\u00f3 junto a m\u00ed mientras yo intentaba resolver la situaci\u00f3n. Mi segunda luz de repuesto se encendi\u00f3, pero ahora me quedaba una sola luz y m\u00e1s de 536 metros (un tercio de milla) para regresar en una cueva submarina.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi compa\u00f1ero me dio una de sus luces de repuesto para que tuviera dos luces que funcionaran bien. Tambi\u00e9n usamos una configuraci\u00f3n de desplazamiento donde est\u00e1bamos en contacto f\u00edsico uno con otro cuando giramos para salir nadando de la cueva. Al hacerlo podr\u00edamos comunicarnos con el tacto si era necesario y pod\u00edamos recurrir a sus luces operativas, y no tendr\u00edamos que buscarnos si mi \u00faltima luz fallaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lentamente regresamos a la entrada, con cuidado al hacer giros para no perder el contacto con el otro. A aproximadamente 305 metros (1.000 pies) de la entrada la luz principal de mi compa\u00f1ero de buceo fall\u00f3 y la cueva se puso completamente negra. Intent\u00f3 encender su luz de repuesto, pero no funcion\u00f3. Ahora nos quedaban solo dos luces que funcionaban entre los dos.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le di su luz de repuesto original, y continuamos avanzando hacia la entrada de la cueva. Mantuvimos el contacto con el otro mientras tambi\u00e9n segu\u00edamos la l\u00ednea con el tacto en caso de que perdi\u00e9ramos la visibilidad debido a un escape de sedimento o m\u00e1s fallas de las luces.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien todas las luces funcionaban en la superficie durante los controles anteriores al buceo, el buceo de ese d\u00eda fue una verdadera prueba para nuestras habilidades en el manejo de luces. A aproximadamente 152 metros (500 pies) de la entrada de la cueva mi \u00faltima luz se apag\u00f3. Guard\u00e9 la luz descompuesta y mir\u00e9 a mi compa\u00f1ero de buceo, que ten\u00eda la \u00fanica luz que nos quedaba, pero claramente estaba perdiendo intensidad. La \u00faltima de nuestras seis luces se apag\u00f3 a aproximadamente 91 metros (300 pies) de la entrada y nos quedamos sin ninguna luz.\u00a0<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"285\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_47_SkillsInAction.jpg\" alt=\"Cave divers carry at least two backup lights\" class=\"wp-image-25928\" style=\"aspect-ratio:1.4027777777777777;width:472px;height:auto\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_47_SkillsInAction.jpg 400w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_47_SkillsInAction-360x257.jpg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_47_SkillsInAction-18x12.jpg 18w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption class=\"wp-element-caption\"><strong>Los buzos de cuevas llevan al menos dos luces de repuesto en caso de que la luz principal falle.<\/strong><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"216\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_48_SkillsInAction.jpg\" alt=\"cave divers using lights\" class=\"wp-image-25929\" style=\"aspect-ratio:1.5138888888888888;width:472px;height:auto\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_48_SkillsInAction.jpg 400w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_48_SkillsInAction-360x194.jpg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_48_SkillsInAction-18x10.jpg 18w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption class=\"wp-element-caption\"><strong>Tener conciencia de equipo es fundamental. Cuando la primera luz de la autora se apag\u00f3, su compa\u00f1ero de equipo pudo voltearse y encontrarla de inmediato porque sab\u00eda d\u00f3nde estaba. <\/strong><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Mi compa\u00f1ero me dio un empujoncito para que continuara nadando hacia adelante en la oscuridad. Tuvimos cuidado de no perder el contacto con el otro o la l\u00ednea \u2014respirando con calma, permaneciendo lo m\u00e1s relajados que pod\u00edamos y movi\u00e9ndonos lentamente para lograr salir de manera segura\u2014. Finalmente vimos un destello de luz proveniente de la entrada de la cueva que brillaba como un faro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Regresamos a la caverna para hacer la descompresi\u00f3n, agradecidos por la luz natural que iluminaba nuestro entorno. Despu\u00e9s de cumplir con nuestra descompresi\u00f3n obligatoria, lentamente salimos de la caverna y nos dirigimos a la superficie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un manejo adecuado de una l\u00ednea es un componente clave del buceo en cuevas. Un buzo de cuevas siempre tiene una l\u00ednea continua de regreso a aguas abiertas y debe estar pendiente de ella en todo momento. Tener conciencia de equipo tambi\u00e9n es fundamental. Cuando mi primera luz se apag\u00f3, mi compa\u00f1ero pudo encontrarme de inmediato porque sab\u00eda d\u00f3nde estaba. Si no hubiera tenido conocimiento de mi ubicaci\u00f3n, evaluar y manejar la situaci\u00f3n hubiera tomado m\u00e1s tiempo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siempre preste atenci\u00f3n a d\u00f3nde se encuentran sus compa\u00f1eros de buceo, cu\u00e1nta mezcla respiratoria tienen y si tienen alg\u00fan problema. Est\u00e9 familiarizado con la configuraci\u00f3n del equipo de su compa\u00f1ero para poder garantizar una respuesta eficiente y sin inconvenientes frente a cualquier problema que surja.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los buzos de cuevas tienen un sistema de redundancia para cada pieza fundamental del equipo, lo que incluye reguladores, tanques y luces. La planificaci\u00f3n para emergencias es importante, pero adquirir habilidades apropiadas y practicar esas habilidades es esencial para la supervivencia. Pasar a nuestras luces de repuesto y utilizar las habilidades que nos hab\u00edan ense\u00f1ado para manejar situaciones en las que las luces se apagan fue memoria muscular para nosotros, lo que minimiz\u00f3 nuestro estr\u00e9s.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los buzos deben aprender a mantener la calma durante un buceo. \u201cLento y relajado con una buena t\u00e9cnica\u201d es un mantra que el instructor de buceo Larry Brown nos ense\u00f1\u00f3 y es una mentalidad fundamental que es importante tener en cada buceo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando todo va seg\u00fan lo previsto, un menor consumo de gas y un mejor control de la flotabilidad se benefician de la respiraci\u00f3n lenta y relajada que conlleva mantener una actitud tranquila durante un buceo. De manera similar, mantener la calma y hacer uso de las habilidades que se han aprendido y practicado mejorar\u00e1 la eficiencia a la hora de responder a emergencias cuando el plan de buceo cambia. AD<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-dan-light-gray-color has-alpha-channel-opacity has-dan-light-gray-background-color has-background is-style-wide\"\/>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">\u00a9&nbsp;<em>Alert Diver<\/em>&nbsp;- Q4 2023<\/p>","protected":false},"excerpt":{"rendered":"<p>MI COMPA\u00d1ERO DE BUCEO Y YO planeamos hacer una inmersi\u00f3n m\u00e1s larga de lo habitual un s\u00e1bado por la ma\u00f1ana en el Parque Estatal Madison Blue Spring en Lee, Florida. Durante varios a\u00f1os y m\u00e1s de 100 inmersiones en cuevas juntos, hab\u00edamos acumulado experiencia como equipo y tiempo de permanencia en este sistema espec\u00edfico de cuevas submarinas del norte de Florida. Poco a poco hab\u00edamos ampliado la duraci\u00f3n y la distancia de nuestras inmersiones en este laberinto de t\u00faneles submarinos que serpenteaban por la piedra caliza k\u00e1rstica del parque, aumentando nuestra familiaridad con el sistema a la vez que practic\u00e1bamos las habilidades que hab\u00edamos aprendido y segu\u00edamos desarrollando para ser buceadores de cuevas seguros.\u00a0<\/p>","protected":false},"featured_media":25927,"template":"","dan_alert_diver_categories":[84],"dan_alert_diver_issues":[488],"class_list":["post-25924","dan_alert_diver","type-dan_alert_diver","status-publish","has-post-thumbnail","hentry","dan_alert_diver_categories-skills-in-action","dan_alert_diver_issues-q4-2023"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Slow and Relaxed with Good Technique - DAN World<\/title>\n<meta name=\"description\" content=\"MY DIVE BUDDY AND I planned to do a longer than usual dive one Saturday morning at Madison Blue Spring State Park in Lee, Florida. For several years and more than 100 cave dives together, we had built up our experience as a team and our time spent in this specific underwater cave system in northern Florida. We had slowly extended the duration and distance of our dives in this labyrinth of underwater tunnels that weaved throughout the karst limestone of the park, increasing our familiarity with the system while also practicing the skills that we had learned and continued to build on to be safe cave divers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slow and Relaxed with Good Technique\" \/>\n<meta property=\"og:description\" content=\"MY DIVE BUDDY AND I planned to do a longer than usual dive one Saturday morning at Madison Blue Spring State Park in Lee, Florida. For several years and more than 100 cave dives together, we had built up our experience as a team and our time spent in this specific underwater cave system in northern Florida. We had slowly extended the duration and distance of our dives in this labyrinth of underwater tunnels that weaved throughout the karst limestone of the park, increasing our familiarity with the system while also practicing the skills that we had learned and continued to build on to be safe cave divers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/world.dan.org\/es\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/\" \/>\n<meta property=\"og:site_name\" content=\"DAN World\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T18:47:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_46_SkillsInAction.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/slow-and-relaxed-with-good-technique\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/slow-and-relaxed-with-good-technique\\\/\",\"name\":\"Slow and Relaxed with Good Technique - DAN World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/slow-and-relaxed-with-good-technique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/slow-and-relaxed-with-good-technique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Q4_46_SkillsInAction.jpg\",\"datePublished\":\"2023-12-11T21:31:31+00:00\",\"dateModified\":\"2024-01-29T18:47:45+00:00\",\"description\":\"MY DIVE BUDDY AND I planned to do a longer than usual dive one Saturday morning at Madison Blue Spring State Park in Lee, Florida. For several years and more than 100 cave dives together, we had built up our experience as a team and our time spent in this specific underwater cave system in northern Florida. We had slowly extended the duration and distance of our dives in this labyrinth of underwater tunnels that weaved throughout the karst limestone of the park, increasing our familiarity with the system while also practicing the skills that we had learned and continued to build on to be safe cave divers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/slow-and-relaxed-with-good-technique\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/slow-and-relaxed-with-good-technique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/slow-and-relaxed-with-good-technique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Q4_46_SkillsInAction.jpg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Q4_46_SkillsInAction.jpg\",\"width\":1200,\"height\":600,\"caption\":\"cave diving in northern Florida\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/slow-and-relaxed-with-good-technique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/world.dan.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slow and Relaxed with Good Technique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"name\":\"DAN World\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/world.dan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\",\"name\":\"DAN World\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"width\":175,\"height\":52,\"caption\":\"DAN World\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Slow and Relaxed with Good Technique - DAN World","description":"MI COMPA\u00d1ERO DE BUCEO Y YO planeamos hacer una inmersi\u00f3n m\u00e1s larga de lo habitual un s\u00e1bado por la ma\u00f1ana en el Parque Estatal Madison Blue Spring en Lee, Florida. Durante varios a\u00f1os y m\u00e1s de 100 inmersiones en cuevas juntos, hab\u00edamos acumulado experiencia como equipo y tiempo de permanencia en este sistema espec\u00edfico de cuevas submarinas del norte de Florida. Poco a poco hab\u00edamos ampliado la duraci\u00f3n y la distancia de nuestras inmersiones en este laberinto de t\u00faneles submarinos que serpenteaban por la piedra caliza k\u00e1rstica del parque, aumentando nuestra familiaridad con el sistema a la vez que practic\u00e1bamos las habilidades que hab\u00edamos aprendido y segu\u00edamos desarrollando para ser buceadores de cuevas seguros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/world.dan.org\/es\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/","og_locale":"es_MX","og_type":"article","og_title":"Slow and Relaxed with Good Technique","og_description":"MY DIVE BUDDY AND I planned to do a longer than usual dive one Saturday morning at Madison Blue Spring State Park in Lee, Florida. For several years and more than 100 cave dives together, we had built up our experience as a team and our time spent in this specific underwater cave system in northern Florida. We had slowly extended the duration and distance of our dives in this labyrinth of underwater tunnels that weaved throughout the karst limestone of the park, increasing our familiarity with the system while also practicing the skills that we had learned and continued to build on to be safe cave divers.","og_url":"https:\/\/world.dan.org\/es\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/","og_site_name":"DAN World","article_modified_time":"2024-01-29T18:47:45+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_46_SkillsInAction.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/world.dan.org\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/","url":"https:\/\/world.dan.org\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/","name":"Slow and Relaxed with Good Technique - DAN World","isPartOf":{"@id":"https:\/\/world.dan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/#primaryimage"},"image":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/#primaryimage"},"thumbnailUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_46_SkillsInAction.jpg","datePublished":"2023-12-11T21:31:31+00:00","dateModified":"2024-01-29T18:47:45+00:00","description":"MI COMPA\u00d1ERO DE BUCEO Y YO planeamos hacer una inmersi\u00f3n m\u00e1s larga de lo habitual un s\u00e1bado por la ma\u00f1ana en el Parque Estatal Madison Blue Spring en Lee, Florida. Durante varios a\u00f1os y m\u00e1s de 100 inmersiones en cuevas juntos, hab\u00edamos acumulado experiencia como equipo y tiempo de permanencia en este sistema espec\u00edfico de cuevas submarinas del norte de Florida. Poco a poco hab\u00edamos ampliado la duraci\u00f3n y la distancia de nuestras inmersiones en este laberinto de t\u00faneles submarinos que serpenteaban por la piedra caliza k\u00e1rstica del parque, aumentando nuestra familiaridad con el sistema a la vez que practic\u00e1bamos las habilidades que hab\u00edamos aprendido y segu\u00edamos desarrollando para ser buceadores de cuevas seguros.","breadcrumb":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/world.dan.org\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/#primaryimage","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_46_SkillsInAction.jpg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/12\/Q4_46_SkillsInAction.jpg","width":1200,"height":600,"caption":"cave diving in northern Florida"},{"@type":"BreadcrumbList","@id":"https:\/\/world.dan.org\/alert-diver\/article\/slow-and-relaxed-with-good-technique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/world.dan.org\/"},{"@type":"ListItem","position":2,"name":"Slow and Relaxed with Good Technique"}]},{"@type":"WebSite","@id":"https:\/\/world.dan.org\/es\/#website","url":"https:\/\/world.dan.org\/es\/","name":"DAN World","description":"","publisher":{"@id":"https:\/\/world.dan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/world.dan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/world.dan.org\/es\/#organization","name":"DAN World","url":"https:\/\/world.dan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","width":175,"height":52,"caption":"DAN World"},"image":{"@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver\/25924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver"}],"about":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/types\/dan_alert_diver"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media\/25927"}],"wp:attachment":[{"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/media?parent=25924"}],"wp:term":[{"taxonomy":"dan_alert_diver_categories","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_categories?post=25924"},{"taxonomy":"dan_alert_diver_issues","embeddable":true,"href":"https:\/\/world.dan.org\/es\/wp-json\/wp\/v2\/dan_alert_diver_issues?post=25924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}