{"id":20930,"date":"2022-04-15T11:47:47","date_gmt":"2022-04-15T15:47:47","guid":{"rendered":"https:\/\/world.dan.org\/?post_type=dan_alert_diver&#038;p=20930"},"modified":"2023-05-22T14:41:52","modified_gmt":"2023-05-22T18:41:52","slug":"mexicos-sardine-run","status":"publish","type":"dan_alert_diver","link":"https:\/\/world.dan.org\/fr\/alert-diver\/article\/mexicos-sardine-run\/","title":{"rendered":"La course aux sardines du Mexique"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Bien que les marlins ray\u00e9s (<em>Kajikia audax<\/em>) sont plus lents que certains de leurs cousins marlins, leur vitesse de 50 milles \u00e0 l'heure est amplement suffisante pour moi. J'essaie de nager \u00e0 c\u00f4t\u00e9 de ce bombardier furtif de la mer pendant qu'il travaille avec une boule d'app\u00e2t pour s\u00e9parer les sardines individuelles de la masse argent\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">While getting outpaced by sailfish and black marlin might be important to striped marlins trying to elude predation, they are so much faster than freediving humans that we don\u2019t usually get close to one. But the Mexico sardine run isn\u2019t normal circumstances, and the marlins aren\u2019t swimming away. They are swimming around, over, under, and through a baitball. If you can stay with the baitball, you can stay with the marlins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">For this reason, underwater photographic encounters with marlins are now very popular in Mexico. It also helps that travel to Mexico is relatively easy, and the seasonal reliability of the sardine aggregations and the attendant predators provides a high probability of a successful encounter. It\u2019s the wild ocean and not an aquarium, so there are no guarantees, but divers and dive operators have refined the protocols for finding baitballs. Sailfish appear off the coast of Isla Mujeres and Cancun from January through March, and striped marlins are accessible at Magdalena Bay on the west coast of Baja California Sur from November through January.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Small pelagic fishes (sardines, anchovies, and mackerels) travel within the California Current, and the timing and location of their congregations influence the upper trophic levels in the food web. The North Pacific Current splits near British Columbia \u2014 the Alaska Current runs north to Alaska, while the California Current travels southward along the West Coast to Baja California. The small pelagics in the California Current are sensitive to\u00a0environmental changes such as El Ni\u00f1o, making them susceptible to any resulting water variations.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/dan.org\/wp-content\/uploads\/2022\/03\/Q1_45_Mexico-Sardine.tif-copy.jpg\" alt=\"marlin ray\u00e9\" class=\"wp-image-30584\"\/><figcaption class=\"wp-element-caption\">Le photographe Amos Nachoum se tient pr\u00e8s de la boule d'app\u00e2t en apn\u00e9e, tandis qu'un makaire ray\u00e9 regarde son repas.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les chercheurs ont identifi\u00e9 trois points culminants le long de la partie sud de Baja o\u00f9 les sardines frayent, pondent, \u00e9closent et atteignent leur maturit\u00e9 :&nbsp;<strong>Baie de Magdalena, Golden Gate Bank<\/strong>&nbsp;pr\u00e8s de Cabo San Lucas, et&nbsp;<strong>Banque des doigts<\/strong>, a<strong>&nbsp;<\/strong>pr\u00e8s de Todos Santos. Prot\u00e9g\u00e9e de l'oc\u00e9an Pacifique par les \u00eeles sablonneuses inhabit\u00e9es de Isla Magdalena et Isla Santa Margarita, la baie de Magdalena (<em>Bah\u00eda Magdalena<\/em>) spans 31 miles along the western coast of the Mexican state of Baja California Sur. By autumn, the sardines have matured enough to attract large predators such as bonitos, striped marlins, Pacific sailfish, sea lions, and even Bryde\u2019s whales.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est extr\u00eamement improbable de trouver par hasard une boule de sardines immerg\u00e9e en pleine mer. Les rencontres r\u00e9ussies se produisent lorsque les plongeurs adoptent les m\u00eames protocoles que les skippers chevronn\u00e9s des flottes de p\u00eache sportive, qui se d\u00e9placent \u00e0 15 ou 20 milles au large et g\u00e9n\u00e9ralement \u00e0 40 ou 50 milles au sud de San Carlos. Les fr\u00e9gates suivent les sardines et nous suivons les fr\u00e9gates. Elles sont nos yeux dans le ciel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frigatebirds search for a meal by flying high enough to see through the water\u2019s surface to the frenzied activity below. As the birds find the baitball, their flight posture changes, and they circle while skimming low over the water. We approach and see the disturbance on the water\u2019s surface as the swarming sardines jump out of the water, creating shiny waves of spray and a cacophony of swishes and splashes as thousands of sardines seek to escape the striped marlins below only to be scooped up by the frigatebirds above. The sardines\u2019 bad luck is our good fortune as we embark on an extraordinary dive adventure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/dan.org\/wp-content\/uploads\/2022\/03\/Q1_46_Mexico-Sardine.tif-copy.jpg\" alt=\"Une mobula\" class=\"wp-image-30588\"\/><figcaption class=\"wp-element-caption\">Une mobula se brise dans la baie de Magdalena.&nbsp;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cGo, go, go!\u201d the divemaster screams at us. I jump into the warm water and search left, right,\u00a0and below. The visibility is at least 80 feet, but I don\u2019t see anything until a\u00a0dozen or more striped marlins suddenly appear out of the blue. I continue swimming and kick harder in the direction the marlins\u00a0are going.\u00a0 Tracking the marlins is tiring, but I keep swimming, confident they know where they are going even if I don\u2019t. Then at the edge of my visibility I see something big, round, and dynamic.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors que je me rapproche, la sph\u00e8re se transforme en une masse fr\u00e9n\u00e9tique et tourbillonnante de petits poissons argent\u00e9s. Les marlins sont d\u00e9j\u00e0 \u00e0 l'attaque. L'un apr\u00e8s l'autre, les marlins foncent vers la proie, hissant leurs voiles, leur corps brillant d'argent et de bleu et refl\u00e9tant des touches de jaune de la lueur d\u00e9clinante de l'apr\u00e8s-midi. Secouant leur queue, ils se rapprochent \u00e0 toute vitesse de la boule d'app\u00e2t, puis ex\u00e9cutent un virage incroyablement serr\u00e9 pour se rapprocher des sardines terrifi\u00e9es. La puissance de leurs becs redoutables est mise en \u00e9vidence lorsqu'ils coupent la boule d'app\u00e2t en deux et entrent en collision avec les poissons sans d\u00e9fense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I am glad digital photography doesn\u2019t limit me to only 36 shots as film did. How could I possibly pace myself with all the constant action? Gratefully, I don\u2019t have to, so I keep photographing the scene.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>&nbsp;<span style=\"color: #005274;\" class=\"stk-highlight\">You will see a range of cameras from smartphones to large digital single-lens reflex and mirrorless cameras. The action occurs in shallow water, and most shooters don\u2019t need strobes \u2026<\/span><\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Some sea lions join the hunt and help the\u00a0marlins with corralling the sardines close to the surface to make feeding easier. The marlins\u00a0are more\u00a0cautious about attacking the baitball when the sea lions are around and search for space between the sea lions\u2019 attacks, perhaps as a precaution to avoid breaking their fragile bills by dashing them against the sea lions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque d'autres otaries arrivent et se gavent de sardines, les marlins se retirent \u00e0 la recherche d'une autre boule d'app\u00e2t. Heureusement, il existe de nombreux autres regroupements de ce type en haute mer, en dehors de la baie de Magdalena.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On pourrait penser qu'il existe une concurrence entre les apn\u00e9istes qui veulent voir un marlin sous l'eau et les p\u00eacheurs qui veulent attraper et d\u00e9barquer un istiophorid\u00e9s. Cependant, si la plong\u00e9e avec des marlins a gagn\u00e9 en popularit\u00e9 parmi les amateurs de plong\u00e9e, l'argent des touristes a profit\u00e9 \u00e0 la communaut\u00e9 locale de p\u00eacheurs de San Carlos. De nombreux patrons de p\u00eache se sont regroup\u00e9s et ont cr\u00e9\u00e9 un syndicat. Les p\u00eacheurs se sont tourn\u00e9s vers l'\u00e9cotourisme, qui leur permet de gagner plus d'argent qu'auparavant, d'exercer moins de pression sur les populations d'istiophorid\u00e9s et, en fin de compte, d'\u00eatre plus sensibilis\u00e9s \u00e0 la conservation et \u00e0 la durabilit\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"wp-block-paragraph\">The area now has an\u00a0influx of people from all over the world. The action attracts\u00a0commercial and\u00a0sportfishing yachts, television and movie productions, and pure nature lovers. You will see a range of cameras from smartphones to large digital single-lens reflex and mirrorless cameras. The action occurs in shallow water, and most shooters don\u2019t need strobes, making for less resistance in the water and greater ease of getting in and out of the panga. During the peak season in November, half a dozen to a dozen vessels might be relatively nearby, but they won\u2019t all be on the same baitball.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les op\u00e9rateurs locaux travaillent ensemble dans le cadre d'une coop\u00e9rative touristique informelle et communiquent par radio maritime, invitant les autres \u00e0 partager leur chance lorsqu'ils trouvent une boule d'app\u00e2t prometteuse. Gr\u00e2ce \u00e0 leur esprit de collaboration, il est presque certain que tous les touristes de passage rentreront chez eux avec des histoires et des images \u00e0 partager. Les guides locaux travaillent d'arrache-pied pour apprendre \u00e0 leurs invit\u00e9s \u00e0 s'approcher en toute s\u00e9curit\u00e9 de la boule d'app\u00e2t sans \u00eatre intrusifs. Les marlins s'en vont lorsque les gens s'approchent trop pr\u00e8s de la boule d'app\u00e2t. L'objectif est donc d'observer la vie marine sans lui mettre la pression.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les op\u00e9rateurs locaux de panga suivent des protocoles de s\u00e9curit\u00e9, notamment en restant en contact radio avec leur base d'attache et entre eux, en revenant toujours \u00e0 terre avant la tomb\u00e9e de la nuit et en signalant lorsqu'ils quittent la zone d'action. Ils rentrent g\u00e9n\u00e9ralement au port en flottille \u00e0 la fin de la journ\u00e9e, ce qui est une disposition prudente pour de petits bateaux \u00e9quip\u00e9s d'un seul moteur hors-bord \u00e0 40 milles des c\u00f4tes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les conditions m\u00e9t\u00e9orologiques jouent un r\u00f4le crucial dans les voyages de plong\u00e9e dans cette r\u00e9gion isol\u00e9e o\u00f9 les services de secours sont limit\u00e9s. Les op\u00e9rateurs suspendent parfois leurs sorties, en particulier en cas de vents violents. Au lieu de prendre le large, les skippers op\u00e8rent dans les eaux plus prot\u00e9g\u00e9es de la baie de Magdalena. M\u00eame si ce n'est pas la destination pr\u00e9vue, la baie peut offrir des rencontres fascinantes. Une vaste zone de dunes de sable situ\u00e9e dans le coin nord-ouest de la baie pr\u00e9sente des canaux d'eau \u00e9labor\u00e9s et un habitat de mangrove sain. On y trouve une population dynamique de poissons, de cormorans, de p\u00e9licans et d'autres esp\u00e8ces d'oiseaux. Vous pouvez m\u00eame apercevoir un coyote ou un pygargue \u00e0 t\u00eate blanche. Cette merveille de mangrove n'est peut-\u00eatre pas l'attrait qui vous am\u00e8nera \u00e0 Magdalena Bay, mais le temps que vous passerez \u00e0 explorer les montagnes d'Isla Magdalena et d'Isla Santa Margarita vous inspirera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De novembre \u00e0 janvier, les boules d'app\u00e2t attirent d'autres animaux que les marlins, notamment les requins tigres. Les requins tigres changent l'ambiance, nous restons donc vigilants et prenons la pr\u00e9caution d'\u00e9teindre les lumi\u00e8res vid\u00e9o vives. Les requins sont tr\u00e8s possessifs \u00e0 l'\u00e9gard de la boule d'app\u00e2t, et nous sommes d\u00e9f\u00e9rents quant \u00e0 notre place dans la cha\u00eene alimentaire.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"288\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_44_mexico-sardine.tif-copy.jpg\" alt=\"Les skippers de San Carlos exploitent des pangas rapides\" class=\"wp-image-21005\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_44_mexico-sardine.tif-copy.jpg 432w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_44_mexico-sardine.tif-copy-360x240.jpg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_44_mexico-sardine.tif-copy-18x12.jpg 18w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><figcaption class=\"wp-element-caption\">Les skippers de San Carlos utilisent des pangas rapides pour suivre les oiseaux, ce qui les conduit aux boules d'app\u00e2t de sardines et \u00e0 leurs pr\u00e9dateurs, les marlins ray\u00e9s.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"288\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_43_mexico-sardine.tif-copy.jpg\" alt=\"L&#039;\u00eele aux oiseaux au c\u0153ur de la baie de Magdalena\" class=\"wp-image-21006\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_43_mexico-sardine.tif-copy.jpg 432w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_43_mexico-sardine.tif-copy-360x240.jpg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_43_mexico-sardine.tif-copy-18x12.jpg 18w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><figcaption class=\"wp-element-caption\">L'\u00eele aux oiseaux, au c\u0153ur de la baie de Magdalena, est une colonie de cormorans et de p\u00e9licans bruns.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"288\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_49_mexico-sardine.tif-copy.jpg\" alt=\"d&#039;immenses bandes de p\u00e9licans en vol\" class=\"wp-image-21007\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_49_mexico-sardine.tif-copy.jpg 432w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_49_mexico-sardine.tif-copy-360x240.jpg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_49_mexico-sardine.tif-copy-18x12.jpg 18w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><figcaption class=\"wp-element-caption\"><span style=\"color: #005274;\" class=\"stk-highlight\">Une exp\u00e9dition au lever du soleil \u00e0<br>L'\u00eele aux oiseaux est r\u00e9compens\u00e9e par l'observation d'immenses vol\u00e9es de p\u00e9licans.<\/span><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dan.org\/wp-content\/uploads\/2022\/03\/Q1_51_Mexico-Sardine.tif-.jpg\" alt=\"un groupe d&#039;orques de passage visite la r\u00e9gion\" class=\"wp-image-30589\" width=\"659\" height=\"439\"\/><figcaption class=\"wp-element-caption\">Quelques fois par saison, un groupe d'orques de passage visite la r\u00e9gion.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pod of orcas visits two or three times during a season, generating much excitement. While we were sitting on the panga a burst of rapid conversation lit up the airwaves. Several pangas left their baitballs to rendezvous with the fisher who spotted the orcas and alerted his buddies. It was extraordinary to swim for two hours with a pod of six transient orcas. One of the females carried a piece of shark meat in her jaw and brought it is close to the panga. After taking a few images of her above water, my team and I joined the pod in the water for a peaceful and nonthreatening encounter \u2014 an experience that will never leave me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En novembre et d\u00e9cembre, les baleines \u00e0 bosse migrent vers le sud, dans les eaux chaudes du Panama et de Socorro, pour socialiser et mettre bas. Nous avons pu nager avec une m\u00e8re et son baleineau \u00e0 plusieurs reprises. Au cours de la m\u00eame saison, une autre \u00e9quipe a v\u00e9cu une exp\u00e9rience remarquable en nageant avec des baleines bleues qui migrent vers le sud en direction de la mer de Cortez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les rencontres avec les raies mobula au large de la baie de Magdalena sont \u00e9galement fantastiques. Lorsque la mer \u00e9tait trop agit\u00e9e pour naviguer vers les zones de sardines et que le vent avait dispers\u00e9 les vol\u00e9es de fr\u00e9gates, notre skipper exp\u00e9riment\u00e9 nous a sugg\u00e9r\u00e9 de prendre le large. Apr\u00e8s une heure ou deux \u00e0 guetter les becs de baleine, quelqu'un a aper\u00e7u un mobula en train de se br\u00e9cher.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">That\u2019s one thing about the Mexican sardine run \u2014 it pays to be flexible. Whatever you thought you might photograph in the morning may not be the images you end up editing at the end of the day. Despite the change in plans, the massive school of mobulas made us very happy.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dan.org\/wp-content\/uploads\/2022\/03\/Q1_47_Mexico-Sardine-copy.jpg\" alt=\"Baleines de Bryde\" class=\"wp-image-30594\" width=\"686\" height=\"447\"\/><figcaption class=\"wp-element-caption\"><strong>&nbsp;<\/strong>Bryde\u2019s whales can engulf almost an entire baitball at once.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Our final notable encounter on this trip was with a Bryde\u2019s whale. Although they are smaller cetaceans, slightly shorter and lighter than humpbacks, Bryde\u2019s whales still take your breath away. The whales may quietly arrive while you are focused on a baitball or darting marlin. With their giant mouths gaping wide, they surprisingly swoop in and engulf almost all the baitball at once.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">If you don\u2019t mind getting up a bit early, you can head out to sea at 5:30 a.m. to see the sunrise over Bird Island. You won\u2019t regret it. The island can accommodate thousands of cormorants and pelicans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En regardant certaines de mes images de drone prises suffisamment haut au-dessus de l'\u00eele pour ne pas perturber les oiseaux en contrebas, j'ai d\u00e9couvert que l'\u00eele avait la forme d'un c\u0153ur. Ce n'est qu'\u00e0 ce moment-l\u00e0 que j'ai d\u00e9couvert le c\u0153ur symbolique de la baie de Magdalena, qui palpite de vie \u00e0 la fois au-dessus et au-dessous de la mer.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-dan-light-gray-color has-alpha-channel-opacity has-dan-light-gray-background-color has-background is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-how-to-dive-it\"><span style=\"color: #005274;\" class=\"stk-highlight\">Comment y plonger<\/span><\/h1>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><span style=\"color: #005274;\" class=\"stk-highlight\">Les lions de mer peuvent souvent se joindre aux marlins pour se gaver d'une boule d'app\u00e2t.<\/span><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"288\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_48_mexico-sardine.jpeg\" alt=\"lions de mer\" class=\"wp-image-20941\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_48_mexico-sardine.jpeg 432w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_48_mexico-sardine-360x240.jpeg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_48_mexico-sardine-18x12.jpeg 18w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Pour s'y rendre :<\/span><\/strong>&nbsp;Des vols sont disponibles pour Loreto, La Paz et Los Cabos. Renseignez-vous aupr\u00e8s de votre voyagiste sur les possibilit\u00e9s de transport en van ou de location de voiture entre l'a\u00e9roport et San Carlos. La meilleure p\u00e9riode pour se rendre dans la baie de Magdalena s'\u00e9tend de novembre \u00e0 janvier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">H\u00e9bergement :<\/span><\/strong>&nbsp;San Carlos compte plusieurs h\u00f4tels de base dont les prix varient entre $50 et $100 par nuit. Tous sont s\u00fbrs et propres, et la nourriture et les boissons mexicaines des cantinas locales sont excellentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Op\u00e9rateurs de plong\u00e9e :<\/span><\/strong>&nbsp;Une coop\u00e9rative de p\u00eache locale propose des op\u00e9rations de plong\u00e9e \u00e0 terre sur des pangas de 25 pieds \u00e9quip\u00e9s de moteurs hors-bord. Des op\u00e9rateurs r\u00e9gionaux organisent des croisi\u00e8res, dont les horaires varient en fonction de la saison et des pr\u00e9f\u00e9rences.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Le mat\u00e9riel :<\/span><\/strong>&nbsp;Apportez au moins un masque, des palmes et un tuba. Les palmes d'apn\u00e9e ne sont pas indispensables, mais elles seront plus efficaces pour ceux qui ont un coup de pied puissant. Une veste coupe-vent et imperm\u00e9able, une polaire chaude, de la cr\u00e8me solaire et des lunettes de soleil sont utiles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">Photographie :<\/span><\/strong>&nbsp;All kinds of cameras will give you amazing images. Telephoto lenses are good for topside photos.\u00a0There is such a wealth of photo opportunities you\u2019ll want something to capture the scene. For underwater photography, plan for wide-angle to superwide lenses. You won\u2019t need strobes.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-dan-light-gray-color has-alpha-channel-opacity has-dan-light-gray-background-color has-background is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-explore-more\"><strong><span style=\"color: #005274;\" class=\"stk-highlight\">En savoir plus<\/span><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Watch a video of Amos Nachoum\u2019s expedition to see striped marlins in Mexico.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Le retour du Marlin\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/WakNIG4JT84?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Although striped marlins (Kajikia audax) are slower than some of their billfish cousins, their 50-mph speed is plenty fast for me. I try to swim alongside this stealth bomber of the sea as it works a baitball to separate individual sardines from the silvery mass. While getting outpaced by sailfish and black marlin might be [\u2026]<\/p>\n","protected":false},"featured_media":20932,"template":"","dan_alert_diver_categories":[73],"dan_alert_diver_issues":[478],"class_list":["post-20930","dan_alert_diver","type-dan_alert_diver","status-publish","has-post-thumbnail","hentry","dan_alert_diver_categories-features","dan_alert_diver_issues-q1-2022"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mexico\u2019s Sardine Run - DAN World<\/title>\n<meta name=\"description\" content=\"Although striped marlins (Kajikia audax) are slower than some of their billfish cousins, their 50-mph speed is plenty fast for me.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/world.dan.org\/fr\/alert-diver\/article\/mexicos-sardine-run\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mexico\u2019s Sardine Run\" \/>\n<meta property=\"og:description\" content=\"Although striped marlins (Kajikia audax) are slower than some of their billfish cousins, their 50-mph speed is plenty fast for me.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/world.dan.org\/fr\/alert-diver\/article\/mexicos-sardine-run\/\" \/>\n<meta property=\"og:site_name\" content=\"DAN World\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T18:41:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_53_mexico-sardine.tif-copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"717\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Although striped marlins (Kajikia audax) are slower than some of their billfish cousins, their 50-mph speed is plenty fast for me.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/mexicos-sardine-run\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/mexicos-sardine-run\\\/\",\"name\":\"Mexico\u2019s Sardine Run - DAN World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/mexicos-sardine-run\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/mexicos-sardine-run\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/q1_53_mexico-sardine.tif-copy.jpg\",\"datePublished\":\"2022-04-15T15:47:47+00:00\",\"dateModified\":\"2023-05-22T18:41:52+00:00\",\"description\":\"Although striped marlins (Kajikia audax) are slower than some of their billfish cousins, their 50-mph speed is plenty fast for me.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/mexicos-sardine-run\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/mexicos-sardine-run\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/mexicos-sardine-run\\\/#primaryimage\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/q1_53_mexico-sardine.tif-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/q1_53_mexico-sardine.tif-copy.jpg\",\"width\":1200,\"height\":717},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/mexicos-sardine-run\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/world.dan.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mexico\u2019s Sardine Run\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"name\":\"DAN World\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/world.dan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\",\"name\":\"DAN World\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"width\":175,\"height\":52,\"caption\":\"DAN World\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La course aux sardines au Mexique - DAN World","description":"Bien que les marlins ray\u00e9s (Kajikia audax) soient plus lents que certains de leurs cousins marlins, leur vitesse de 50 milles \u00e0 l'heure me convient parfaitement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/world.dan.org\/fr\/alert-diver\/article\/mexicos-sardine-run\/","og_locale":"fr_CA","og_type":"article","og_title":"Mexico\u2019s Sardine Run","og_description":"Although striped marlins (Kajikia audax) are slower than some of their billfish cousins, their 50-mph speed is plenty fast for me.","og_url":"https:\/\/world.dan.org\/fr\/alert-diver\/article\/mexicos-sardine-run\/","og_site_name":"DAN World","article_modified_time":"2023-05-22T18:41:52+00:00","og_image":[{"width":1200,"height":717,"url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_53_mexico-sardine.tif-copy.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"Although striped marlins (Kajikia audax) are slower than some of their billfish cousins, their 50-mph speed is plenty fast for me.","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/world.dan.org\/alert-diver\/article\/mexicos-sardine-run\/","url":"https:\/\/world.dan.org\/alert-diver\/article\/mexicos-sardine-run\/","name":"La course aux sardines au Mexique - DAN World","isPartOf":{"@id":"https:\/\/world.dan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/mexicos-sardine-run\/#primaryimage"},"image":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/mexicos-sardine-run\/#primaryimage"},"thumbnailUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_53_mexico-sardine.tif-copy.jpg","datePublished":"2022-04-15T15:47:47+00:00","dateModified":"2023-05-22T18:41:52+00:00","description":"Bien que les marlins ray\u00e9s (Kajikia audax) soient plus lents que certains de leurs cousins marlins, leur vitesse de 50 milles \u00e0 l'heure me convient parfaitement.","breadcrumb":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/mexicos-sardine-run\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/world.dan.org\/alert-diver\/article\/mexicos-sardine-run\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/world.dan.org\/alert-diver\/article\/mexicos-sardine-run\/#primaryimage","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_53_mexico-sardine.tif-copy.jpg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/q1_53_mexico-sardine.tif-copy.jpg","width":1200,"height":717},{"@type":"BreadcrumbList","@id":"https:\/\/world.dan.org\/alert-diver\/article\/mexicos-sardine-run\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/world.dan.org\/"},{"@type":"ListItem","position":2,"name":"Mexico\u2019s Sardine Run"}]},{"@type":"WebSite","@id":"https:\/\/world.dan.org\/es\/#website","url":"https:\/\/world.dan.org\/es\/","name":"DAN World","description":"","publisher":{"@id":"https:\/\/world.dan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/world.dan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/world.dan.org\/es\/#organization","name":"DAN World","url":"https:\/\/world.dan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","width":175,"height":52,"caption":"DAN World"},"image":{"@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/dan_alert_diver\/20930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/dan_alert_diver"}],"about":[{"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/types\/dan_alert_diver"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/media\/20932"}],"wp:attachment":[{"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/media?parent=20930"}],"wp:term":[{"taxonomy":"dan_alert_diver_categories","embeddable":true,"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/dan_alert_diver_categories?post=20930"},{"taxonomy":"dan_alert_diver_issues","embeddable":true,"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/dan_alert_diver_issues?post=20930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}