{"id":24051,"date":"2023-03-27T15:10:59","date_gmt":"2023-03-27T19:10:59","guid":{"rendered":"https:\/\/world.dan.org\/?post_type=dan_alert_diver&#038;p=24051"},"modified":"2023-05-09T10:05:16","modified_gmt":"2023-05-09T14:05:16","slug":"the-dive-light-a-tool-for-all-divers","status":"publish","type":"dan_alert_diver","link":"https:\/\/world.dan.org\/fr\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","title":{"rendered":"La lampe de plong\u00e9e : Un outil pour tous les plongeurs"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.addtoany.com\/share\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'\u00e9clairage de plong\u00e9e est un \u00e9quipement essentiel qui peut \u00eatre utile \u00e0 tous les plongeurs lors de la plupart des plong\u00e9es. Il existe plusieurs types d'\u00e9clairages avec des utilisations diff\u00e9rentes et quelques consid\u00e9rations cl\u00e9s \u00e0 prendre en compte avant l'achat. Il n'existe pas d'approche unique en mati\u00e8re d'\u00e9clairage de plong\u00e9e. Chaque plongeur doit donc examiner attentivement ses propres objectifs et besoins avant de choisir le mod\u00e8le le plus utile.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-dive-light-uses\">Utilisation des lampes de plong\u00e9e<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les plongeurs pensent souvent que les lampes servent uniquement \u00e0 \u00e9clairer ce qui se trouve sous la surface lors des plong\u00e9es nocturnes, mais ce n'est qu'une application parmi d'autres. Lors des plong\u00e9es o\u00f9 il n'y a pas de lumi\u00e8re ambiante (comme la plong\u00e9e de nuit ou la plong\u00e9e en grotte), les lampes de plong\u00e9e \u00e9clairent votre environnement, mais vous pouvez \u00e9galement les utiliser pour communiquer avec d'autres plongeurs.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec la lumi\u00e8re ambiante, les lampes de plong\u00e9e peuvent restaurer les couleurs perdues avec la profondeur, aider \u00e0 prendre des photos de haute qualit\u00e9 de la vie sous-marine et \u00e9clairer les petites cr\u00e9atures sous les corniches ou dans les crevasses. Vous pouvez utiliser les lampes de plong\u00e9e pour communiquer dans ces conditions, mais vos signaux seront probablement plus difficiles \u00e0 voir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un phare de plong\u00e9e peut \u00e9galement aider \u00e0 signaler une situation d'urgence au-dessus ou au-dessous de l'eau. Un mouvement rapide de va-et-vient sous l'eau indique que le plongeur est en d\u00e9tresse. En surface, un phare de plong\u00e9e peut attirer l'attention du bateau de plong\u00e9e ou d'un h\u00e9licopt\u00e8re de sauvetage, \u00e0 condition que les conditions permettent de le voir de loin.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les utilisations non traditionnelles des lampes de plong\u00e9e, citons l'\u00e9clairage d'un drapeau de plong\u00e9e remorqu\u00e9 par un plongeur la nuit ou l'\u00e9clairage d'un pavillon pour l'installation du mat\u00e9riel apr\u00e8s le coucher du soleil. Un fabricant encourage m\u00eame ses clients \u00e0 utiliser leurs lampes autour d'un grill ext\u00e9rieur pour les collations d'apr\u00e8s-plong\u00e9e. Cependant, tous les \u00e9clairages de plong\u00e9e ne peuvent pas fonctionner en toute s\u00e9curit\u00e9 lorsqu'ils sont hors de l'eau pendant de longues p\u00e9riodes.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Types de lampes de plong\u00e9e<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque type d'\u00e9clairage de plong\u00e9e a des applications uniques. Les plongeurs amateurs utilisent g\u00e9n\u00e9ralement des lampes portatives sans fil, faciles \u00e0 transporter et \u00e0 utiliser, et dont le prix est g\u00e9n\u00e9ralement raisonnable. Les plongeurs techniques pr\u00e9f\u00e8rent souvent les \u00e9clairages en bo\u00eete pour leur dur\u00e9e de vie plus longue et la possibilit\u00e9 de les faire tomber sans perdre la t\u00eate de l'\u00e9clairage. Plusieurs fabricants ont mis au point des lampes sans fil dont les caract\u00e9ristiques sont similaires \u00e0 celles des lampes \u00e0 bo\u00eete, ce qui a incit\u00e9 de nombreux plongeurs techniques \u00e0 les adopter.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les lampes LED (diode \u00e9lectroluminescente) sont de plus en plus populaires en raison de la puissance de leur faisceau, mais certains plongeurs pr\u00e9f\u00e8rent les lampes HID (d\u00e9charge \u00e0 haute intensit\u00e9) dont le faisceau fonctionne bien dans les eaux troubles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les plongeurs doivent \u00e9galement prendre en compte les options de montage. Certains utilisent une poign\u00e9e Goodman rigide ou souple, tandis que d'autres utilisent une dragonne. Les lampes de plong\u00e9e peuvent \u00e9galement \u00eatre mont\u00e9es sur la sangle du masque ou sur le casque.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_51_gear.jpg\" alt=\"Les plongeurs sp\u00e9l\u00e9ologues choisissent souvent d&#039;utiliser des lampes \u00e0 canister\" class=\"wp-image-24054\" width=\"297\" height=\"445\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_51_gear.jpg 534w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_51_gear-240x360.jpg 240w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_51_gear-8x12.jpg 8w\" sizes=\"auto, (max-width: 297px) 100vw, 297px\" \/><figcaption class=\"wp-element-caption\">Cave divers often choose to use canister lights because of their longer burn times.\n\u00a9NATALIE L. GIBB<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear.jpg\" alt=\"Plusieurs lampes sur le march\u00e9 aujourd&#039;hui\" class=\"wp-image-24055\" width=\"592\" height=\"333\" srcset=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear.jpg 800w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear-360x203.jpg 360w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear-768x432.jpg 768w, https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_53_gear-18x10.jpg 18w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><figcaption class=\"wp-element-caption\">Several lights on the market today suit the needs of most divers. \n\u00a9KYLE HABECKER<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Consid\u00e9rations avant l'achat<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">High-quality dive lights are expensive, and divers should educate themselves before purchasing one. The intended application governs the burn time you\u2019ll need. A cave diver, for example, needs longer burn times than an open-water diver doing daytime reef dives.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Your needs and uses will help determine what intensity (measured in lumens) and coverage (measured in lux, or lumens per square meter) you\u2019ll want in the dive light\u2019s beam. The beam angle is also crucial for using light to communicate. The tighter the beam, the easier it is to discern signals. The beam\u2019s visibility is especially critical in conditions without ambient light or on technical dives that require clear and concise team communication.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est important d'acheter une lampe de plong\u00e9e aupr\u00e8s d'un fabricant r\u00e9put\u00e9. La qualit\u00e9 et la fiabilit\u00e9 de leurs produits sont prouv\u00e9es, et il est plus facile d'obtenir des r\u00e9parations fiables et de l'aide gr\u00e2ce \u00e0 l'assistance client\u00e8le.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conseils et astuces<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle que soit la lampe de plong\u00e9e que vous choisissez, certains conseils peuvent vous aider \u00e0 rendre la plong\u00e9e plus s\u00fbre et plus agr\u00e9able.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">You should perform a burn test on all dive lights every six to 12 months. Turn on your fully charged lights and put them in a bucket of water. Record the time it takes for the battery to die, and track any changes from previous tests. Burn tests help divers identify when it is time to replace batteries to optimize the lights\u2019 performance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Divers should use proper light etiquette while in the water. Keep the beam forward and stable as much as possible. Move the beam slowly, and avoid jerky movements that others may mistake as emergency signals. Pay attention to where you point it so that you don\u2019t shine it directly into other divers\u2019 eyes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le plongeur en t\u00eate d'un groupe doit envisager de r\u00e9duire l'intensit\u00e9 de son \u00e9clairage. Cette pratique permet aux lumi\u00e8res des personnes qui suivent d'\u00eatre plus visibles, ce qui am\u00e9liore la communication au sein de l'\u00e9quipe et rend la plong\u00e9e plus s\u00fbre.&nbsp;<\/p>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">\u00a9&nbsp;<em>Alert Diver<\/em>&nbsp;- Q1 2023<\/p>","protected":false},"excerpt":{"rendered":"<p>L'\u00e9clairage de plong\u00e9e est un \u00e9quipement essentiel qui peut \u00eatre utile \u00e0 tous les plongeurs lors de la plupart des plong\u00e9es. Il existe plusieurs types d'\u00e9clairages avec des utilisations diff\u00e9rentes et quelques consid\u00e9rations cl\u00e9s \u00e0 prendre en compte avant l'achat. Il n'existe pas d'approche unique en mati\u00e8re d'\u00e9clairage de plong\u00e9e. Chaque plongeur doit donc examiner attentivement ses propres objectifs et besoins avant de choisir le mod\u00e8le le plus utile.<\/p>","protected":false},"featured_media":24052,"template":"","dan_alert_diver_categories":[71],"dan_alert_diver_issues":[484],"class_list":["post-24051","dan_alert_diver","type-dan_alert_diver","status-publish","has-post-thumbnail","hentry","dan_alert_diver_categories-gear","dan_alert_diver_issues-q1-2023"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Dive Light: A Tool for All Divers - DAN World<\/title>\n<meta name=\"description\" content=\"The dive light is essential equipment that can benefit all divers on most dives. There are several types of lights with various uses and a few key considerations you should make before purchasing.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/world.dan.org\/fr\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Dive Light: A Tool for All Divers\" \/>\n<meta property=\"og:description\" content=\"The dive light is essential equipment that can benefit all divers on most dives. There are several types of lights with various uses and a few key considerations you should make before purchasing.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/world.dan.org\/fr\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/\" \/>\n<meta property=\"og:site_name\" content=\"DAN World\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-09T14:05:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"The dive light is essential equipment that can benefit all divers on most dives.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/\",\"name\":\"The Dive Light: A Tool for All Divers - DAN World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/q1_52_gear.jpg\",\"datePublished\":\"2023-03-27T19:10:59+00:00\",\"dateModified\":\"2023-05-09T14:05:16+00:00\",\"description\":\"The dive light is essential equipment that can benefit all divers on most dives. There are several types of lights with various uses and a few key considerations you should make before purchasing.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/q1_52_gear.jpg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/q1_52_gear.jpg\",\"width\":1200,\"height\":1132,\"caption\":\"Lights are tools for all divers, even when ambient light is present. \u00a9STEPHEN FRINK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/alert-diver\\\/article\\\/the-dive-light-a-tool-for-all-divers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/world.dan.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Dive Light: A Tool for All Divers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"name\":\"DAN World\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/world.dan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#organization\",\"name\":\"DAN World\",\"url\":\"https:\\\/\\\/world.dan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"contentUrl\":\"https:\\\/\\\/world.dan.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DAN-World-logo-sm-52px.svg\",\"width\":175,\"height\":52,\"caption\":\"DAN World\"},\"image\":{\"@id\":\"https:\\\/\\\/world.dan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La lampe de plong\u00e9e : Un outil pour tous les plongeurs - DAN World","description":"L'\u00e9clairage de plong\u00e9e est un \u00e9quipement essentiel qui peut \u00eatre utile \u00e0 tous les plongeurs lors de la plupart des plong\u00e9es. Il existe plusieurs types d'\u00e9clairages avec des utilisations diff\u00e9rentes et quelques consid\u00e9rations cl\u00e9s \u00e0 prendre en compte avant l'achat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/world.dan.org\/fr\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","og_locale":"fr_CA","og_type":"article","og_title":"The Dive Light: A Tool for All Divers","og_description":"The dive light is essential equipment that can benefit all divers on most dives. There are several types of lights with various uses and a few key considerations you should make before purchasing.","og_url":"https:\/\/world.dan.org\/fr\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","og_site_name":"DAN World","article_modified_time":"2023-05-09T14:05:16+00:00","og_image":[{"width":1200,"height":1132,"url":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"The dive light is essential equipment that can benefit all divers on most dives.","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","url":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/","name":"La lampe de plong\u00e9e : Un outil pour tous les plongeurs - DAN World","isPartOf":{"@id":"https:\/\/world.dan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#primaryimage"},"image":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#primaryimage"},"thumbnailUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg","datePublished":"2023-03-27T19:10:59+00:00","dateModified":"2023-05-09T14:05:16+00:00","description":"L'\u00e9clairage de plong\u00e9e est un \u00e9quipement essentiel qui peut \u00eatre utile \u00e0 tous les plongeurs lors de la plupart des plong\u00e9es. Il existe plusieurs types d'\u00e9clairages avec des utilisations diff\u00e9rentes et quelques consid\u00e9rations cl\u00e9s \u00e0 prendre en compte avant l'achat.","breadcrumb":{"@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#primaryimage","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2023\/04\/q1_52_gear.jpg","width":1200,"height":1132,"caption":"Lights are tools for all divers, even when ambient light is present. \u00a9STEPHEN FRINK"},{"@type":"BreadcrumbList","@id":"https:\/\/world.dan.org\/alert-diver\/article\/the-dive-light-a-tool-for-all-divers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/world.dan.org\/"},{"@type":"ListItem","position":2,"name":"The Dive Light: A Tool for All Divers"}]},{"@type":"WebSite","@id":"https:\/\/world.dan.org\/es\/#website","url":"https:\/\/world.dan.org\/es\/","name":"DAN World","description":"","publisher":{"@id":"https:\/\/world.dan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/world.dan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/world.dan.org\/es\/#organization","name":"DAN World","url":"https:\/\/world.dan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","contentUrl":"https:\/\/world.dan.org\/wp-content\/uploads\/2022\/04\/DAN-World-logo-sm-52px.svg","width":175,"height":52,"caption":"DAN World"},"image":{"@id":"https:\/\/world.dan.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/dan_alert_diver\/24051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/dan_alert_diver"}],"about":[{"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/types\/dan_alert_diver"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/media\/24052"}],"wp:attachment":[{"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/media?parent=24051"}],"wp:term":[{"taxonomy":"dan_alert_diver_categories","embeddable":true,"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/dan_alert_diver_categories?post=24051"},{"taxonomy":"dan_alert_diver_issues","embeddable":true,"href":"https:\/\/world.dan.org\/fr\/wp-json\/wp\/v2\/dan_alert_diver_issues?post=24051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}